{"id":731,"date":"2022-04-12T08:38:10","date_gmt":"2022-04-12T06:38:10","guid":{"rendered":"https:\/\/desdelaterrazadeamador.com\/?p=731"},"modified":"2022-04-12T08:38:12","modified_gmt":"2022-04-12T06:38:12","slug":"un-camarero-de-bar-robotizado","status":"publish","type":"post","link":"https:\/\/desdelaterrazadeamador.com\/en\/un-camarero-de-bar-robotizado\/","title":{"rendered":"A robot bartender"},"content":{"rendered":"<p>Views: 9<\/p>\n<p class=\"wp-block-paragraph\">This robot has turned out to be one of the sensations of the MWC 2022 Fair, a robotic waiter that is capable of attending in 10 languages, recognizing its clients, and serving cocktails and other drinks (beers, coffees, etc\u2026) during the 24 hours of the day, and without ever asking for a raise or getting sick. Although perhaps sometime it breaks down and has to be repaired.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">It has been presented by the Spanish company Macco Robotics and it has other types of robotic products on the market, such as a delivery car, an automated disinfection system for interiors, etc\u2026 It is a company dedicated to robotics for services to people.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I liked the idea because it is a completely autonomous system that can be moved to any location. It can be placed in any establishment using very little of its space, as can be seen in the photo below.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/04\/Robot-Camarero.png\" alt=\"\" class=\"wp-image-732\" width=\"421\" height=\"340\" srcset=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/04\/Robot-Camarero.png 300w, https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/04\/Robot-Camarero-15x12.png 15w\" sizes=\"auto, (max-width: 421px) 100vw, 421px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">The company has had the good idea of giving the robot a \"human\" aspect so that it attracts more customers, and I am sure that it has been the \"business\" of the MWC 2022 Fair that has billed the most this year, since it can be easily paid with a credit card.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A video can be seen at: <a href=\"https:\/\/youtu.be\/LaZ0tNFlLNk\">https:\/\/youtu.be\/LaZ0tNFlLNk<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">It is placed in just 2 m3 of space and is capable of serving more than 250 drinks per hour. And since the idea is \u201cmodular\u201d, two robotic modules can be placed next to each other, each serving 10 different or complementary products.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I have been saying for a long time that robots have a very good future ahead of them, and this is just one more example. That said, a simple idea that can be well received in the market and I wish it very sincerely. Hopefully they find many customers around the world.<\/p>","protected":false},"excerpt":{"rendered":"<p>Views: 9 Este robot ha resultado ser una de las sensaciones de la Feria MWC 2022, un camarero robotizado que es capaz de atender en 10 idiomas, reconocer a sus clientes, y servir cocktails y otras bebidas ( cervezas, caf\u00e9s, etc \u2026 ) durante las 24 horas del d\u00eda, y sin pedir nunca un aumento [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":485,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[116,118],"tags":[],"class_list":["post-731","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-robotics","category-robots"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un camarero de bar robotizado - Desde la terraza de Amador<\/title>\n<meta name=\"description\" content=\"Este robot ha resultado ser una de las sensaciones de la Feria MWC 2022, un camarero robotizado que es capaz de atender en 10 idiomas, reconocer a sus\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desdelaterrazadeamador.com\/en\/un-camarero-de-bar-robotizado\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un camarero de bar robotizado - Desde la terraza de Amador\" \/>\n<meta property=\"og:description\" content=\"Este robot ha resultado ser una de las sensaciones de la Feria MWC 2022, un camarero robotizado que es capaz de atender en 10 idiomas, reconocer a sus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desdelaterrazadeamador.com\/en\/un-camarero-de-bar-robotizado\/\" \/>\n<meta property=\"og:site_name\" content=\"Desde la terraza de Amador\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-12T06:38:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-12T06:38:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Robot-MODELO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Amador Palacios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/edurneamaya\" \/>\n<meta name=\"twitter:site\" content=\"@edurneamaya\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amador Palacios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/un-camarero-de-bar-robotizado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/un-camarero-de-bar-robotizado\\\/\"},\"author\":{\"name\":\"Amador Palacios\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"headline\":\"Un camarero de bar robotizado\",\"datePublished\":\"2022-04-12T06:38:10+00:00\",\"dateModified\":\"2022-04-12T06:38:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/un-camarero-de-bar-robotizado\\\/\"},\"wordCount\":313,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"image\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/un-camarero-de-bar-robotizado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Robot-MODELO.jpg\",\"articleSection\":[\"Robotics\",\"Robots\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/desdelaterrazadeamador.com\\\/un-camarero-de-bar-robotizado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/un-camarero-de-bar-robotizado\\\/\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/un-camarero-de-bar-robotizado\\\/\",\"name\":\"Un camarero de bar robotizado - Desde la terraza de Amador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/un-camarero-de-bar-robotizado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/un-camarero-de-bar-robotizado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Robot-MODELO.jpg\",\"datePublished\":\"2022-04-12T06:38:10+00:00\",\"dateModified\":\"2022-04-12T06:38:12+00:00\",\"description\":\"Este robot ha resultado ser una de las sensaciones de la Feria MWC 2022, un camarero robotizado que es capaz de atender en 10 idiomas, reconocer a sus\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/un-camarero-de-bar-robotizado\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desdelaterrazadeamador.com\\\/un-camarero-de-bar-robotizado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/un-camarero-de-bar-robotizado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Robot-MODELO.jpg\",\"contentUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Robot-MODELO.jpg\",\"width\":500,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/un-camarero-de-bar-robotizado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un camarero de bar robotizado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#website\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/\",\"name\":\"Desde la terraza de Amador\",\"description\":\"Reflexiones libres y honestas sobre temas de actualidad social y tecnol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\",\"name\":\"Amador Palacios\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"contentUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"width\":1265,\"height\":899,\"caption\":\"Amador Palacios\"},\"logo\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\"},\"description\":\"Reflexiones de Amador Palacios sobre temas de Actualidad Social y Tecnol\u00f3gica; otras opiniones diferentes a la m\u00eda son bienvenidas\",\"sameAs\":[\"http:\\\/\\\/desdelaterrazadeamador.com\",\"https:\\\/\\\/es.linkedin.com\\\/in\\\/amador-palacios-499532a\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/edurneamaya\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un camarero de bar robotizado - Desde la terraza de Amador","description":"Este robot ha resultado ser una de las sensaciones de la Feria MWC 2022, un camarero robotizado que es capaz de atender en 10 idiomas, reconocer a sus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desdelaterrazadeamador.com\/en\/un-camarero-de-bar-robotizado\/","og_locale":"en_US","og_type":"article","og_title":"Un camarero de bar robotizado - Desde la terraza de Amador","og_description":"Este robot ha resultado ser una de las sensaciones de la Feria MWC 2022, un camarero robotizado que es capaz de atender en 10 idiomas, reconocer a sus","og_url":"https:\/\/desdelaterrazadeamador.com\/en\/un-camarero-de-bar-robotizado\/","og_site_name":"Desde la terraza de Amador","article_published_time":"2022-04-12T06:38:10+00:00","article_modified_time":"2022-04-12T06:38:12+00:00","og_image":[{"width":500,"height":375,"url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Robot-MODELO.jpg","type":"image\/jpeg"}],"author":"Amador Palacios","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/edurneamaya","twitter_site":"@edurneamaya","twitter_misc":{"Written by":"Amador Palacios","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/desdelaterrazadeamador.com\/un-camarero-de-bar-robotizado\/#article","isPartOf":{"@id":"https:\/\/desdelaterrazadeamador.com\/un-camarero-de-bar-robotizado\/"},"author":{"name":"Amador Palacios","@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"headline":"Un camarero de bar robotizado","datePublished":"2022-04-12T06:38:10+00:00","dateModified":"2022-04-12T06:38:12+00:00","mainEntityOfPage":{"@id":"https:\/\/desdelaterrazadeamador.com\/un-camarero-de-bar-robotizado\/"},"wordCount":313,"commentCount":0,"publisher":{"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"image":{"@id":"https:\/\/desdelaterrazadeamador.com\/un-camarero-de-bar-robotizado\/#primaryimage"},"thumbnailUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Robot-MODELO.jpg","articleSection":["Robotics","Robots"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/desdelaterrazadeamador.com\/un-camarero-de-bar-robotizado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/desdelaterrazadeamador.com\/un-camarero-de-bar-robotizado\/","url":"https:\/\/desdelaterrazadeamador.com\/un-camarero-de-bar-robotizado\/","name":"Un camarero de bar robotizado - Desde la terraza de Amador","isPartOf":{"@id":"https:\/\/desdelaterrazadeamador.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/desdelaterrazadeamador.com\/un-camarero-de-bar-robotizado\/#primaryimage"},"image":{"@id":"https:\/\/desdelaterrazadeamador.com\/un-camarero-de-bar-robotizado\/#primaryimage"},"thumbnailUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Robot-MODELO.jpg","datePublished":"2022-04-12T06:38:10+00:00","dateModified":"2022-04-12T06:38:12+00:00","description":"Este robot ha resultado ser una de las sensaciones de la Feria MWC 2022, un camarero robotizado que es capaz de atender en 10 idiomas, reconocer a sus","breadcrumb":{"@id":"https:\/\/desdelaterrazadeamador.com\/un-camarero-de-bar-robotizado\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desdelaterrazadeamador.com\/un-camarero-de-bar-robotizado\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/desdelaterrazadeamador.com\/un-camarero-de-bar-robotizado\/#primaryimage","url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Robot-MODELO.jpg","contentUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Robot-MODELO.jpg","width":500,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/desdelaterrazadeamador.com\/un-camarero-de-bar-robotizado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/desdelaterrazadeamador.com\/"},{"@type":"ListItem","position":2,"name":"Un camarero de bar robotizado"}]},{"@type":"WebSite","@id":"https:\/\/desdelaterrazadeamador.com\/#website","url":"https:\/\/desdelaterrazadeamador.com\/","name":"Desde la terraza de Amador","description":"Free and honest reflections on current social and technological issues","publisher":{"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desdelaterrazadeamador.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66","name":"Amador Palacios","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","contentUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","width":1265,"height":899,"caption":"Amador Palacios"},"logo":{"@id":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg"},"description":"Reflexiones de Amador Palacios sobre temas de Actualidad Social y Tecnol\u00f3gica; otras opiniones diferentes a la m\u00eda son bienvenidas","sameAs":["http:\/\/desdelaterrazadeamador.com","https:\/\/es.linkedin.com\/in\/amador-palacios-499532a","https:\/\/x.com\/https:\/\/twitter.com\/edurneamaya"]}]}},"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/comments?post=731"}],"version-history":[{"count":1,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/731\/revisions"}],"predecessor-version":[{"id":733,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/731\/revisions\/733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/media\/485"}],"wp:attachment":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/media?parent=731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/categories?post=731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/tags?post=731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}