{"id":468,"date":"2022-01-12T09:05:03","date_gmt":"2022-01-12T08:05:03","guid":{"rendered":"https:\/\/desdelaterrazadeamador.com\/?p=468"},"modified":"2022-01-12T09:05:05","modified_gmt":"2022-01-12T08:05:05","slug":"son-mejores-las-tostadoras-actuales-que-las-de-antes","status":"publish","type":"post","link":"https:\/\/desdelaterrazadeamador.com\/en\/son-mejores-las-tostadoras-actuales-que-las-de-antes\/","title":{"rendered":"Are today's toasters better than the old ones?"},"content":{"rendered":"<p>Views: 24<\/p>\n<p class=\"wp-block-paragraph\">There are products that have not changed much over time, because they solve a very simple need, such as toasters. They have existed for over 70 years and they do the same thing by toasting a piece of bread.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The idea for this reflection was given to me by a great article by <a href=\"https:\/\/www.theverge.com\/authors\/sean-hollister\">Sean Hollister<\/a><a href=\"https:\/\/www.twitter.com\/StarFire2258\">@StarFire2258<\/a> in The Verge magazine, in which he compares a current toaster with one made in 1948<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As this nice man says very well, toasters continue doing the same as always, toasting a few slices of bread. And that was already done very well and very reliably 70 years ago, and also with a certain technology, because when the bread was placed, it was automatically introduced into the toaster, it was toasted on both sides and after toasting, it was ejected to the exterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">They were robust, reliable, easy to repair devices that lasted for many years of continuous use.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">An \u201cold\u201d toaster is shown in the photo below.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Tostadora-Sunbeam.jpg\" alt=\"\" class=\"wp-image-469\" width=\"544\" height=\"443\" srcset=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Tostadora-Sunbeam.jpg 400w, https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Tostadora-Sunbeam-300x245.jpg 300w, https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Tostadora-Sunbeam-15x12.jpg 15w\" sizes=\"auto, (max-width: 544px) 100vw, 544px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">And you can see a great video at: <a href=\"https:\/\/youtu.be\/1OfxlSG6q5Y\">https:\/\/youtu.be\/1OfxlSG6q5Y<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\"Modern\" toasters have more buttons and displays, but they do the same thing. They toast bread.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">And my reflection is: Why do we need to complicate things unnecessarily? As someone very well said a long time ago: <strong>Keep It Simple Stupid<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Complicating things unnecessarily is the dumbest thing in the world, and it\u2019s done continuously with a multitude of products, taking advantage of the enormous possibilities that technology offers us.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">For example, today all kinds of products are connected to the Internet, although in many cases it is not necessary, and not even convenient, as it is a way to facilitate the entry of hackers into our house.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anyway, dear friends, enjoy your products but remember that the simpler they are, the less problems they will give you.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">And I thank Sean Hollister again for giving me insight into my today\u2019s reflection.<\/p>","protected":false},"excerpt":{"rendered":"<p>Views: 24 Hay productos que no han cambiado mucho con el tiempo, porque resuelven una necesidad muy sencilla, como es el caso de las tostadoras. Existen desde hace 70 a\u00f1os y hacen lo mismo tostar un pan. La idea de esta reflexi\u00f3n me la ha dado un estupendo art\u00edculo de Sean Hollister@StarFire2258 en la revista [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":470,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[135],"tags":[],"class_list":["post-468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technology"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bf Son mejores las tostadoras actuales que las de antes ? - Desde la terraza de Amador<\/title>\n<meta name=\"description\" content=\"Hay productos que no han cambiado mucho con el tiempo, porque resuelven una necesidad muy sencilla, como es el caso de las tostadoras. Existen desde hace\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desdelaterrazadeamador.com\/en\/son-mejores-las-tostadoras-actuales-que-las-de-antes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bf Son mejores las tostadoras actuales que las de antes ? - Desde la terraza de Amador\" \/>\n<meta property=\"og:description\" content=\"Hay productos que no han cambiado mucho con el tiempo, porque resuelven una necesidad muy sencilla, como es el caso de las tostadoras. Existen desde hace\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desdelaterrazadeamador.com\/en\/son-mejores-las-tostadoras-actuales-que-las-de-antes\/\" \/>\n<meta property=\"og:site_name\" content=\"Desde la terraza de Amador\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-12T08:05:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-12T08:05:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Tostadora-modelo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"431\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Amador Palacios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/edurneamaya\" \/>\n<meta name=\"twitter:site\" content=\"@edurneamaya\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amador Palacios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/son-mejores-las-tostadoras-actuales-que-las-de-antes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/son-mejores-las-tostadoras-actuales-que-las-de-antes\\\/\"},\"author\":{\"name\":\"Amador Palacios\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"headline\":\"\u00bf Son mejores las tostadoras actuales que las de antes ?\",\"datePublished\":\"2022-01-12T08:05:03+00:00\",\"dateModified\":\"2022-01-12T08:05:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/son-mejores-las-tostadoras-actuales-que-las-de-antes\\\/\"},\"wordCount\":345,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"image\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/son-mejores-las-tostadoras-actuales-que-las-de-antes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Tostadora-modelo.jpg\",\"articleSection\":[\"Technology\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/desdelaterrazadeamador.com\\\/son-mejores-las-tostadoras-actuales-que-las-de-antes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/son-mejores-las-tostadoras-actuales-que-las-de-antes\\\/\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/son-mejores-las-tostadoras-actuales-que-las-de-antes\\\/\",\"name\":\"\u00bf Son mejores las tostadoras actuales que las de antes ? - Desde la terraza de Amador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/son-mejores-las-tostadoras-actuales-que-las-de-antes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/son-mejores-las-tostadoras-actuales-que-las-de-antes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Tostadora-modelo.jpg\",\"datePublished\":\"2022-01-12T08:05:03+00:00\",\"dateModified\":\"2022-01-12T08:05:05+00:00\",\"description\":\"Hay productos que no han cambiado mucho con el tiempo, porque resuelven una necesidad muy sencilla, como es el caso de las tostadoras. Existen desde hace\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/son-mejores-las-tostadoras-actuales-que-las-de-antes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desdelaterrazadeamador.com\\\/son-mejores-las-tostadoras-actuales-que-las-de-antes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/son-mejores-las-tostadoras-actuales-que-las-de-antes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Tostadora-modelo.jpg\",\"contentUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Tostadora-modelo.jpg\",\"width\":500,\"height\":431},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/son-mejores-las-tostadoras-actuales-que-las-de-antes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bf Son mejores las tostadoras actuales que las de antes ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#website\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/\",\"name\":\"Desde la terraza de Amador\",\"description\":\"Reflexiones libres y honestas sobre temas de actualidad social y tecnol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\",\"name\":\"Amador Palacios\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"contentUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"width\":1265,\"height\":899,\"caption\":\"Amador Palacios\"},\"logo\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\"},\"description\":\"Reflexiones de Amador Palacios sobre temas de Actualidad Social y Tecnol\u00f3gica; otras opiniones diferentes a la m\u00eda son bienvenidas\",\"sameAs\":[\"http:\\\/\\\/desdelaterrazadeamador.com\",\"https:\\\/\\\/es.linkedin.com\\\/in\\\/amador-palacios-499532a\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/edurneamaya\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bf Son mejores las tostadoras actuales que las de antes ? - Desde la terraza de Amador","description":"Hay productos que no han cambiado mucho con el tiempo, porque resuelven una necesidad muy sencilla, como es el caso de las tostadoras. Existen desde hace","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desdelaterrazadeamador.com\/en\/son-mejores-las-tostadoras-actuales-que-las-de-antes\/","og_locale":"en_US","og_type":"article","og_title":"\u00bf Son mejores las tostadoras actuales que las de antes ? - Desde la terraza de Amador","og_description":"Hay productos que no han cambiado mucho con el tiempo, porque resuelven una necesidad muy sencilla, como es el caso de las tostadoras. Existen desde hace","og_url":"https:\/\/desdelaterrazadeamador.com\/en\/son-mejores-las-tostadoras-actuales-que-las-de-antes\/","og_site_name":"Desde la terraza de Amador","article_published_time":"2022-01-12T08:05:03+00:00","article_modified_time":"2022-01-12T08:05:05+00:00","og_image":[{"width":500,"height":431,"url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Tostadora-modelo.jpg","type":"image\/jpeg"}],"author":"Amador Palacios","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/edurneamaya","twitter_site":"@edurneamaya","twitter_misc":{"Written by":"Amador Palacios","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/desdelaterrazadeamador.com\/son-mejores-las-tostadoras-actuales-que-las-de-antes\/#article","isPartOf":{"@id":"https:\/\/desdelaterrazadeamador.com\/son-mejores-las-tostadoras-actuales-que-las-de-antes\/"},"author":{"name":"Amador Palacios","@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"headline":"\u00bf Son mejores las tostadoras actuales que las de antes ?","datePublished":"2022-01-12T08:05:03+00:00","dateModified":"2022-01-12T08:05:05+00:00","mainEntityOfPage":{"@id":"https:\/\/desdelaterrazadeamador.com\/son-mejores-las-tostadoras-actuales-que-las-de-antes\/"},"wordCount":345,"commentCount":0,"publisher":{"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"image":{"@id":"https:\/\/desdelaterrazadeamador.com\/son-mejores-las-tostadoras-actuales-que-las-de-antes\/#primaryimage"},"thumbnailUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Tostadora-modelo.jpg","articleSection":["Technology"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/desdelaterrazadeamador.com\/son-mejores-las-tostadoras-actuales-que-las-de-antes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/desdelaterrazadeamador.com\/son-mejores-las-tostadoras-actuales-que-las-de-antes\/","url":"https:\/\/desdelaterrazadeamador.com\/son-mejores-las-tostadoras-actuales-que-las-de-antes\/","name":"\u00bf Son mejores las tostadoras actuales que las de antes ? - Desde la terraza de Amador","isPartOf":{"@id":"https:\/\/desdelaterrazadeamador.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/desdelaterrazadeamador.com\/son-mejores-las-tostadoras-actuales-que-las-de-antes\/#primaryimage"},"image":{"@id":"https:\/\/desdelaterrazadeamador.com\/son-mejores-las-tostadoras-actuales-que-las-de-antes\/#primaryimage"},"thumbnailUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Tostadora-modelo.jpg","datePublished":"2022-01-12T08:05:03+00:00","dateModified":"2022-01-12T08:05:05+00:00","description":"Hay productos que no han cambiado mucho con el tiempo, porque resuelven una necesidad muy sencilla, como es el caso de las tostadoras. Existen desde hace","breadcrumb":{"@id":"https:\/\/desdelaterrazadeamador.com\/son-mejores-las-tostadoras-actuales-que-las-de-antes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desdelaterrazadeamador.com\/son-mejores-las-tostadoras-actuales-que-las-de-antes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/desdelaterrazadeamador.com\/son-mejores-las-tostadoras-actuales-que-las-de-antes\/#primaryimage","url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Tostadora-modelo.jpg","contentUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Tostadora-modelo.jpg","width":500,"height":431},{"@type":"BreadcrumbList","@id":"https:\/\/desdelaterrazadeamador.com\/son-mejores-las-tostadoras-actuales-que-las-de-antes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/desdelaterrazadeamador.com\/"},{"@type":"ListItem","position":2,"name":"\u00bf Son mejores las tostadoras actuales que las de antes ?"}]},{"@type":"WebSite","@id":"https:\/\/desdelaterrazadeamador.com\/#website","url":"https:\/\/desdelaterrazadeamador.com\/","name":"Desde la terraza de Amador","description":"Free and honest reflections on current social and technological issues","publisher":{"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desdelaterrazadeamador.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66","name":"Amador Palacios","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","contentUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","width":1265,"height":899,"caption":"Amador Palacios"},"logo":{"@id":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg"},"description":"Reflexiones de Amador Palacios sobre temas de Actualidad Social y Tecnol\u00f3gica; otras opiniones diferentes a la m\u00eda son bienvenidas","sameAs":["http:\/\/desdelaterrazadeamador.com","https:\/\/es.linkedin.com\/in\/amador-palacios-499532a","https:\/\/x.com\/https:\/\/twitter.com\/edurneamaya"]}]}},"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/comments?post=468"}],"version-history":[{"count":1,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/468\/revisions"}],"predecessor-version":[{"id":471,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/468\/revisions\/471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/media\/470"}],"wp:attachment":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/media?parent=468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/categories?post=468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/tags?post=468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}