{"id":4431,"date":"2026-04-17T08:08:07","date_gmt":"2026-04-17T06:08:07","guid":{"rendered":"https:\/\/desdelaterrazadeamador.com\/?p=4431"},"modified":"2026-04-19T08:01:09","modified_gmt":"2026-04-19T06:01:09","slug":"otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias","status":"publish","type":"post","link":"https:\/\/desdelaterrazadeamador.com\/en\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\/","title":{"rendered":"Another company claims to have found the \u201cHoly Grail\u201d of batteries"},"content":{"rendered":"<p>Views: 13<\/p>\n<p class=\"wp-block-paragraph\">Every so often, a new company appears announcing that it has found the \u201cHoly Grail\u201d of batteries. A technology that promises to be cheaper, safer, have higher energy density, and be able to charge in minutes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">And, as I always say, I hope it's true. But it's also wise to maintain a healthy dose of skepticism, because the recent history of batteries is full of grand promises that then take years\u2014or decades\u2014to materialize.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Today, almost everything depends on a battery. From a mobile phone, a laptop, or wireless headphones, to something much larger like an electric car or an energy storage system for the electrical grid.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">That's why there is intensive research being conducted worldwide on new energy storage technologies.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The ideal battery should meet several requirements: High energy density (storing a lot of energy in a small space), low cost, high safety, long lifespan, and fast charging.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">And achieving all of that at the same time is no easy feat. That's why the lithium battery remains the queen, which, we must remember, began to be developed in the 1970s and started to become popular in the early 1990s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde entonces han evolucionado much\u00edsimo. Hoy existen diferentes variantes qu\u00edmicas, mejoras en seguridad, optimizaci\u00f3n en densidad energ\u00e9tica y reducci\u00f3n de costes. Gracias a estas mejoras, las bater\u00edas de litio son actualmente la base de:\u00a0 smartphones, ordenadores port\u00e1tiles, veh\u00edculos el\u00e9ctricos, etc \u2026\u00a0\u00a0\u00a0\u00a0 Y, por supuesto, tambi\u00e9n de gran parte de los sistemas de almacenamiento de energ\u00eda renovable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Even so, the industry continues to search for the next big revolution, with solid-state batteries holding promise. On paper, solid-state batteries have several potential advantages that could reshape the current market. It's a technology that is also being researched by major companies in the automotive and technology sectors.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In this context, a US company called ION Storage Systems has emerged. The company claims to have developed a solid-state battery that has passed customer validation tests.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"334\" src=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2026\/04\/Bateria-ION.jpg\" alt=\"\" class=\"wp-image-4433\" srcset=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2026\/04\/Bateria-ION.jpg 500w, https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2026\/04\/Bateria-ION-300x200.jpg 300w, https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2026\/04\/Bateria-ION-18x12.jpg 18w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">But they don't provide any technical data. And this is where the part that raises doubts for me comes in.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">You can visit their website at: <a href=\"https:\/\/ionstoragesystems.com\/\">https:\/\/ionstoragesystems.com\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">After reading several articles about this battery and visiting the company's website, I haven't found any concrete technical data on the technology's performance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">For example, it would be interesting to know: energy density (Wh\/kg), number of charge cycles, recharge times, estimated costs, and thermal stability.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Without this type of information, it's difficult to truly assess the scope of the technological advancement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">This doesn't necessarily mean the technology isn't promising. There may be strategic or commercial reasons for not yet publishing this data. But it's true that the lack of transparency generates a certain amount of skepticism.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Furthermore, there's another factor that's often overlooked. Developing a functional prototype in a laboratory is one thing. Manufacturing millions of units reliably, economically, and consistently is quite another.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">That industrial leap is usually the biggest challenge in any new battery technology. It requires enormous investment, years of engineering, and a completely optimized supply chain.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">According to the company itself, they plan to begin manufacturing in 2026, initially focusing on electronics customers before expanding into larger applications.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As with many innovations in the energy sector, only time will tell if this technology truly represents a significant breakthrough or if it remains just another empty promise.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Let's hope it's the former.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Views: 13 Cada cierto tiempo aparece una nueva empresa anunciando que ha encontrado el \u201cSanto Grial\u201d de las bater\u00edas. Una tecnolog\u00eda que promete ser m\u00e1s barata, m\u00e1s segura, con mayor densidad energ\u00e9tica y capaz de cargarse en minutos. Y, como siempre digo, ojal\u00e1 sea verdad. Pero tambi\u00e9n conviene mantener cierto escepticismo sano, porque la historia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[124,174,153,135,155],"tags":[],"class_list":["post-4431","post","type-post","status-publish","format-standard","hentry","category-electric-cars","category-energy","category-industry","category-technology","category-transportation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Otra empresa que dice haber encontrado el \u201cSanto Grial\u201d de las bater\u00edas - Desde la terraza de Amador<\/title>\n<meta name=\"description\" content=\"Cada cierto tiempo aparece una nueva empresa anunciando que ha encontrado el \u201cSanto Grial\u201d de las bater\u00edas. Una tecnolog\u00eda que promete ser m\u00e1s barata, m\u00e1s\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desdelaterrazadeamador.com\/en\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Otra empresa que dice haber encontrado el \u201cSanto Grial\u201d de las bater\u00edas - Desde la terraza de Amador\" \/>\n<meta property=\"og:description\" content=\"Cada cierto tiempo aparece una nueva empresa anunciando que ha encontrado el \u201cSanto Grial\u201d de las bater\u00edas. Una tecnolog\u00eda que promete ser m\u00e1s barata, m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desdelaterrazadeamador.com\/en\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\/\" \/>\n<meta property=\"og:site_name\" content=\"Desde la terraza de Amador\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-17T06:08:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-19T06:01:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2026\/04\/Bateria-ION.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"334\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Amador Palacios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/edurneamaya\" \/>\n<meta name=\"twitter:site\" content=\"@edurneamaya\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amador Palacios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\\\/\"},\"author\":{\"name\":\"Amador Palacios\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"headline\":\"Otra empresa que dice haber encontrado el \u201cSanto Grial\u201d de las bater\u00edas\",\"datePublished\":\"2026-04-17T06:08:07+00:00\",\"dateModified\":\"2026-04-19T06:01:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\\\/\"},\"wordCount\":662,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"image\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Bateria-ION.jpg\",\"articleSection\":[\"Electric cars\",\"Energy\",\"Industry\",\"Technology\",\"Transportation\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/desdelaterrazadeamador.com\\\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\\\/\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\\\/\",\"name\":\"Otra empresa que dice haber encontrado el \u201cSanto Grial\u201d de las bater\u00edas - Desde la terraza de Amador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Bateria-ION.jpg\",\"datePublished\":\"2026-04-17T06:08:07+00:00\",\"dateModified\":\"2026-04-19T06:01:09+00:00\",\"description\":\"Cada cierto tiempo aparece una nueva empresa anunciando que ha encontrado el \u201cSanto Grial\u201d de las bater\u00edas. Una tecnolog\u00eda que promete ser m\u00e1s barata, m\u00e1s\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desdelaterrazadeamador.com\\\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Bateria-ION.jpg\",\"contentUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Bateria-ION.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Otra empresa que dice haber encontrado el \u201cSanto Grial\u201d de las bater\u00edas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#website\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/\",\"name\":\"Desde la terraza de Amador\",\"description\":\"Reflexiones libres y honestas sobre temas de actualidad social y tecnol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\",\"name\":\"Amador Palacios\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"contentUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"width\":1265,\"height\":899,\"caption\":\"Amador Palacios\"},\"logo\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\"},\"description\":\"Reflexiones de Amador Palacios sobre temas de Actualidad Social y Tecnol\u00f3gica; otras opiniones diferentes a la m\u00eda son bienvenidas\",\"sameAs\":[\"http:\\\/\\\/desdelaterrazadeamador.com\",\"https:\\\/\\\/es.linkedin.com\\\/in\\\/amador-palacios-499532a\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/edurneamaya\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Otra empresa que dice haber encontrado el \u201cSanto Grial\u201d de las bater\u00edas - Desde la terraza de Amador","description":"Cada cierto tiempo aparece una nueva empresa anunciando que ha encontrado el \u201cSanto Grial\u201d de las bater\u00edas. Una tecnolog\u00eda que promete ser m\u00e1s barata, m\u00e1s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desdelaterrazadeamador.com\/en\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\/","og_locale":"en_US","og_type":"article","og_title":"Otra empresa que dice haber encontrado el \u201cSanto Grial\u201d de las bater\u00edas - Desde la terraza de Amador","og_description":"Cada cierto tiempo aparece una nueva empresa anunciando que ha encontrado el \u201cSanto Grial\u201d de las bater\u00edas. Una tecnolog\u00eda que promete ser m\u00e1s barata, m\u00e1s","og_url":"https:\/\/desdelaterrazadeamador.com\/en\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\/","og_site_name":"Desde la terraza de Amador","article_published_time":"2026-04-17T06:08:07+00:00","article_modified_time":"2026-04-19T06:01:09+00:00","og_image":[{"width":500,"height":334,"url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2026\/04\/Bateria-ION.jpg","type":"image\/jpeg"}],"author":"Amador Palacios","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/edurneamaya","twitter_site":"@edurneamaya","twitter_misc":{"Written by":"Amador Palacios","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/desdelaterrazadeamador.com\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\/#article","isPartOf":{"@id":"https:\/\/desdelaterrazadeamador.com\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\/"},"author":{"name":"Amador Palacios","@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"headline":"Otra empresa que dice haber encontrado el \u201cSanto Grial\u201d de las bater\u00edas","datePublished":"2026-04-17T06:08:07+00:00","dateModified":"2026-04-19T06:01:09+00:00","mainEntityOfPage":{"@id":"https:\/\/desdelaterrazadeamador.com\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\/"},"wordCount":662,"commentCount":0,"publisher":{"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"image":{"@id":"https:\/\/desdelaterrazadeamador.com\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\/#primaryimage"},"thumbnailUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2026\/04\/Bateria-ION.jpg","articleSection":["Electric cars","Energy","Industry","Technology","Transportation"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/desdelaterrazadeamador.com\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/desdelaterrazadeamador.com\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\/","url":"https:\/\/desdelaterrazadeamador.com\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\/","name":"Otra empresa que dice haber encontrado el \u201cSanto Grial\u201d de las bater\u00edas - Desde la terraza de Amador","isPartOf":{"@id":"https:\/\/desdelaterrazadeamador.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/desdelaterrazadeamador.com\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\/#primaryimage"},"image":{"@id":"https:\/\/desdelaterrazadeamador.com\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\/#primaryimage"},"thumbnailUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2026\/04\/Bateria-ION.jpg","datePublished":"2026-04-17T06:08:07+00:00","dateModified":"2026-04-19T06:01:09+00:00","description":"Cada cierto tiempo aparece una nueva empresa anunciando que ha encontrado el \u201cSanto Grial\u201d de las bater\u00edas. Una tecnolog\u00eda que promete ser m\u00e1s barata, m\u00e1s","breadcrumb":{"@id":"https:\/\/desdelaterrazadeamador.com\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desdelaterrazadeamador.com\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/desdelaterrazadeamador.com\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\/#primaryimage","url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2026\/04\/Bateria-ION.jpg","contentUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2026\/04\/Bateria-ION.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/desdelaterrazadeamador.com\/otra-empresa-que-dice-haber-encontrado-el-santo-grial-de-las-baterias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/desdelaterrazadeamador.com\/"},{"@type":"ListItem","position":2,"name":"Otra empresa que dice haber encontrado el \u201cSanto Grial\u201d de las bater\u00edas"}]},{"@type":"WebSite","@id":"https:\/\/desdelaterrazadeamador.com\/#website","url":"https:\/\/desdelaterrazadeamador.com\/","name":"Desde la terraza de Amador","description":"Free and honest reflections on current social and technological issues","publisher":{"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desdelaterrazadeamador.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66","name":"Amador Palacios","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","contentUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","width":1265,"height":899,"caption":"Amador Palacios"},"logo":{"@id":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg"},"description":"Reflexiones de Amador Palacios sobre temas de Actualidad Social y Tecnol\u00f3gica; otras opiniones diferentes a la m\u00eda son bienvenidas","sameAs":["http:\/\/desdelaterrazadeamador.com","https:\/\/es.linkedin.com\/in\/amador-palacios-499532a","https:\/\/x.com\/https:\/\/twitter.com\/edurneamaya"]}]}},"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/4431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/comments?post=4431"}],"version-history":[{"count":3,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/4431\/revisions"}],"predecessor-version":[{"id":4440,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/4431\/revisions\/4440"}],"wp:attachment":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/media?parent=4431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/categories?post=4431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/tags?post=4431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}