{"id":4376,"date":"2026-03-30T09:10:36","date_gmt":"2026-03-30T07:10:36","guid":{"rendered":"https:\/\/desdelaterrazadeamador.com\/?p=4376"},"modified":"2026-04-03T08:28:09","modified_gmt":"2026-04-03T06:28:09","slug":"toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion","status":"publish","type":"post","link":"https:\/\/desdelaterrazadeamador.com\/en\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\/","title":{"rendered":"Toyota boosts Joby's production: When aviation learns from the automotive Industry"},"content":{"rendered":"<p>Views: 32<\/p>\n<p class=\"wp-block-paragraph\">The urban air mobility sector is advancing rapidly, but manufacturing safe aircraft is not the same as designing attractive prototypes. This is where a strategic alliance that can make all the difference comes into play.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Joby Aviation, specializing in electric vertical takeoff and landing (eVTOL) aircraft for passenger transport, has already invested around $2.2 billion in its project. Of that amount, more than $900 million comes from Toyota Motor Corporation, which therefore owns more than 30% of the company.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Joby is at a critical stage: manufacturing prototypes for certification and real-world operational testing. The company aims to begin commercial flights in Dubai in 2026, an ambitious goal in a sector where timelines are often extended.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">To bolster this phase, Toyota has sent several dozen expert operators to Joby's assembly plant in Santa Cruz, California. Their mission is not to supervise, but to train and optimize production processes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">It's a smart move. Designing a flying vehicle is complex. Manufacturing it repeatably, safely, and to aeronautical standards is even more demanding.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toyota is not just a car manufacturer. It's a global benchmark for industrial excellence thanks to the Toyota Production System (TPS), a model based on efficiency, continuous improvement, waste elimination, and exhaustive quality control. This system has allowed the company to produce millions of vehicles with high levels of reliability and safety.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Transferring that industrial culture to an aerospace startup can be decisive. In aviation, every screw, every wire, and every procedure must be perfectly documented and traced. It's not enough for the design to be good; the manufacturing process must be flawless, and the aircraft's flight completely safe.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2026\/03\/Joby-fabricacion.jpg\" alt=\"\" class=\"wp-image-4377\" style=\"width:390px;height:auto\" srcset=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2026\/03\/Joby-fabricacion.jpg 300w, https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2026\/03\/Joby-fabricacion-18x12.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">The aeronautical world is extremely rigorous, and it should be. Aircraft certification by the Federal Aviation Administration is a lengthy, technical, and demanding process.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aerospace companies with decades of experience take years to certify new models. Joby, as a relatively young company, faces an even greater challenge, even though its aircraft isn't overly complex compared to a large airplane.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Safety is non-negotiable. Every component must demonstrate structural reliability, redundancy in critical systems, and resilience under extreme conditions.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">That's why Toyota's support is so important. Optimizing processes from the outset can prevent costly delays later on and facilitate future production increases.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Joby has stated its intention to manufacture up to four aircrafts per month by 2027. On paper, this is a reasonable goal if certification proceeds as planned.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">But there's often a considerable gap between intention and execution. Scaling up production in the aerospace industry isn't simply a matter of increasing work shifts. It requires certified suppliers, rigorous quality controls, and an extremely reliable supply chain.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">This is where Toyota's industrial DNA can contribute discipline and methodology. It's a long-term strategic bet. Toyota has understood that investing capital isn't enough. It's also necessary to transfer productive knowledge.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The eVTOL market promises to transform urban mobility in the coming decades. If this model thrives, we could see networks of electric air taxis connecting airports and city centers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">This news is positive because it demonstrates real commitment. If Joby manages to certify its aircraft and scale production with robust standards, both companies could benefit enormously.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As always in emerging technology sectors, the timeline is uncertain. But when aeronautical engineering combines with Japanese industrial excellence, the result deserves attention.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Time, as always, will tell.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Views: 32 El sector de la movilidad a\u00e9rea urbana avanza r\u00e1pido, pero fabricar aeronaves seguras no es lo mismo que dise\u00f1ar prototipos atractivos. Aqu\u00ed es donde entra en juego una alianza estrat\u00e9gica que puede marcar diferencias. Joby Aviation, especializada en aeronaves el\u00e9ctricas de despegue y aterrizaje vertical (eVTOL) para transporte de pasajeros, ha invertido ya [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[104,122,153,167,135,155],"tags":[],"class_list":["post-4376","post","type-post","status-publish","format-standard","hentry","category-aeronautics","category-electric-airplanes","category-industry","category-sustainable-transport","category-technology","category-transportation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Toyota impulsa la producci\u00f3n de Joby: cuando la aviaci\u00f3n aprende de la automoci\u00f3n - Desde la terraza de Amador<\/title>\n<meta name=\"description\" content=\"El sector de la movilidad a\u00e9rea urbana avanza r\u00e1pido, pero fabricar aeronaves seguras no es lo mismo que dise\u00f1ar prototipos atractivos. Aqu\u00ed es donde\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desdelaterrazadeamador.com\/en\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Toyota impulsa la producci\u00f3n de Joby: cuando la aviaci\u00f3n aprende de la automoci\u00f3n - Desde la terraza de Amador\" \/>\n<meta property=\"og:description\" content=\"El sector de la movilidad a\u00e9rea urbana avanza r\u00e1pido, pero fabricar aeronaves seguras no es lo mismo que dise\u00f1ar prototipos atractivos. Aqu\u00ed es donde\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desdelaterrazadeamador.com\/en\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\/\" \/>\n<meta property=\"og:site_name\" content=\"Desde la terraza de Amador\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-30T07:10:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-03T06:28:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2026\/03\/Joby-fabricacion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Amador Palacios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/edurneamaya\" \/>\n<meta name=\"twitter:site\" content=\"@edurneamaya\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amador Palacios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\\\/\"},\"author\":{\"name\":\"Amador Palacios\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"headline\":\"Toyota impulsa la producci\u00f3n de Joby: cuando la aviaci\u00f3n aprende de la automoci\u00f3n\",\"datePublished\":\"2026-03-30T07:10:36+00:00\",\"dateModified\":\"2026-04-03T06:28:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\\\/\"},\"wordCount\":661,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"image\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Joby-fabricacion.jpg\",\"articleSection\":[\"Aeronautics\",\"Electric airplanes\",\"Industry\",\"Sustainable Transport\",\"Technology\",\"Transportation\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/desdelaterrazadeamador.com\\\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\\\/\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\\\/\",\"name\":\"Toyota impulsa la producci\u00f3n de Joby: cuando la aviaci\u00f3n aprende de la automoci\u00f3n - Desde la terraza de Amador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Joby-fabricacion.jpg\",\"datePublished\":\"2026-03-30T07:10:36+00:00\",\"dateModified\":\"2026-04-03T06:28:09+00:00\",\"description\":\"El sector de la movilidad a\u00e9rea urbana avanza r\u00e1pido, pero fabricar aeronaves seguras no es lo mismo que dise\u00f1ar prototipos atractivos. Aqu\u00ed es donde\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desdelaterrazadeamador.com\\\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Joby-fabricacion.jpg\",\"contentUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Joby-fabricacion.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Toyota impulsa la producci\u00f3n de Joby: cuando la aviaci\u00f3n aprende de la automoci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#website\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/\",\"name\":\"Desde la terraza de Amador\",\"description\":\"Reflexiones libres y honestas sobre temas de actualidad social y tecnol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\",\"name\":\"Amador Palacios\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"contentUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"width\":1265,\"height\":899,\"caption\":\"Amador Palacios\"},\"logo\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\"},\"description\":\"Reflexiones de Amador Palacios sobre temas de Actualidad Social y Tecnol\u00f3gica; otras opiniones diferentes a la m\u00eda son bienvenidas\",\"sameAs\":[\"http:\\\/\\\/desdelaterrazadeamador.com\",\"https:\\\/\\\/es.linkedin.com\\\/in\\\/amador-palacios-499532a\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/edurneamaya\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Toyota impulsa la producci\u00f3n de Joby: cuando la aviaci\u00f3n aprende de la automoci\u00f3n - Desde la terraza de Amador","description":"El sector de la movilidad a\u00e9rea urbana avanza r\u00e1pido, pero fabricar aeronaves seguras no es lo mismo que dise\u00f1ar prototipos atractivos. Aqu\u00ed es donde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desdelaterrazadeamador.com\/en\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\/","og_locale":"en_US","og_type":"article","og_title":"Toyota impulsa la producci\u00f3n de Joby: cuando la aviaci\u00f3n aprende de la automoci\u00f3n - Desde la terraza de Amador","og_description":"El sector de la movilidad a\u00e9rea urbana avanza r\u00e1pido, pero fabricar aeronaves seguras no es lo mismo que dise\u00f1ar prototipos atractivos. Aqu\u00ed es donde","og_url":"https:\/\/desdelaterrazadeamador.com\/en\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\/","og_site_name":"Desde la terraza de Amador","article_published_time":"2026-03-30T07:10:36+00:00","article_modified_time":"2026-04-03T06:28:09+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2026\/03\/Joby-fabricacion.jpg","type":"image\/jpeg"}],"author":"Amador Palacios","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/edurneamaya","twitter_site":"@edurneamaya","twitter_misc":{"Written by":"Amador Palacios","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/desdelaterrazadeamador.com\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\/#article","isPartOf":{"@id":"https:\/\/desdelaterrazadeamador.com\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\/"},"author":{"name":"Amador Palacios","@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"headline":"Toyota impulsa la producci\u00f3n de Joby: cuando la aviaci\u00f3n aprende de la automoci\u00f3n","datePublished":"2026-03-30T07:10:36+00:00","dateModified":"2026-04-03T06:28:09+00:00","mainEntityOfPage":{"@id":"https:\/\/desdelaterrazadeamador.com\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\/"},"wordCount":661,"commentCount":0,"publisher":{"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"image":{"@id":"https:\/\/desdelaterrazadeamador.com\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\/#primaryimage"},"thumbnailUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2026\/03\/Joby-fabricacion.jpg","articleSection":["Aeronautics","Electric airplanes","Industry","Sustainable Transport","Technology","Transportation"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/desdelaterrazadeamador.com\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/desdelaterrazadeamador.com\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\/","url":"https:\/\/desdelaterrazadeamador.com\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\/","name":"Toyota impulsa la producci\u00f3n de Joby: cuando la aviaci\u00f3n aprende de la automoci\u00f3n - Desde la terraza de Amador","isPartOf":{"@id":"https:\/\/desdelaterrazadeamador.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/desdelaterrazadeamador.com\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\/#primaryimage"},"image":{"@id":"https:\/\/desdelaterrazadeamador.com\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\/#primaryimage"},"thumbnailUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2026\/03\/Joby-fabricacion.jpg","datePublished":"2026-03-30T07:10:36+00:00","dateModified":"2026-04-03T06:28:09+00:00","description":"El sector de la movilidad a\u00e9rea urbana avanza r\u00e1pido, pero fabricar aeronaves seguras no es lo mismo que dise\u00f1ar prototipos atractivos. Aqu\u00ed es donde","breadcrumb":{"@id":"https:\/\/desdelaterrazadeamador.com\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desdelaterrazadeamador.com\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/desdelaterrazadeamador.com\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\/#primaryimage","url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2026\/03\/Joby-fabricacion.jpg","contentUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2026\/03\/Joby-fabricacion.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/desdelaterrazadeamador.com\/toyota-impulsa-la-produccion-de-joby-cuando-la-aviacion-aprende-de-la-automocion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/desdelaterrazadeamador.com\/"},{"@type":"ListItem","position":2,"name":"Toyota impulsa la producci\u00f3n de Joby: cuando la aviaci\u00f3n aprende de la automoci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/desdelaterrazadeamador.com\/#website","url":"https:\/\/desdelaterrazadeamador.com\/","name":"Desde la terraza de Amador","description":"Free and honest reflections on current social and technological issues","publisher":{"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desdelaterrazadeamador.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66","name":"Amador Palacios","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","contentUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","width":1265,"height":899,"caption":"Amador Palacios"},"logo":{"@id":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg"},"description":"Reflexiones de Amador Palacios sobre temas de Actualidad Social y Tecnol\u00f3gica; otras opiniones diferentes a la m\u00eda son bienvenidas","sameAs":["http:\/\/desdelaterrazadeamador.com","https:\/\/es.linkedin.com\/in\/amador-palacios-499532a","https:\/\/x.com\/https:\/\/twitter.com\/edurneamaya"]}]}},"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/4376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/comments?post=4376"}],"version-history":[{"count":1,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/4376\/revisions"}],"predecessor-version":[{"id":4378,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/4376\/revisions\/4378"}],"wp:attachment":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/media?parent=4376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/categories?post=4376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/tags?post=4376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}