{"id":2860,"date":"2024-05-16T08:23:05","date_gmt":"2024-05-16T06:23:05","guid":{"rendered":"https:\/\/desdelaterrazadeamador.com\/?p=2860"},"modified":"2024-05-19T08:07:38","modified_gmt":"2024-05-19T06:07:38","slug":"los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad","status":"publish","type":"post","link":"https:\/\/desdelaterrazadeamador.com\/en\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\/","title":{"rendered":"Modern cars are one of the biggest risks to our privacy and security"},"content":{"rendered":"<p>Views: 21<\/p>\n<p class=\"wp-block-paragraph\">Modern cars, especially electric ones, have become complex computer systems on wheels. Its computer system controls the entire operation of the vehicle, from the engine and transmission to infotainment and safety functions. In addition, they collect a large amount of data about us, our environment and our driving habits.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">It is clear that this technology offers convenience and efficiency, but it also presents significant risks to our privacy and security. And in my opinion the worst of all is the absolute lack of transparency, since we have no idea what data is collected, how it is used and with whom it is shared.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Data may be shared with auto manufacturers, insurance companies, service providers and, in some cases, government authorities. And in the case of a dictatorial government, it could, in theory, modify the car's software to be able to control it at its mercy.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"230\" height=\"230\" src=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2024\/05\/Coche-moderno-electrico.jpg\" alt=\"\" class=\"wp-image-2861\" style=\"width:359px;height:auto\" srcset=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2024\/05\/Coche-moderno-electrico.jpg 230w, https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2024\/05\/Coche-moderno-electrico-150x150.jpg 150w, https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2024\/05\/Coche-moderno-electrico-12x12.jpg 12w\" sizes=\"auto, (max-width: 230px) 100vw, 230px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">I've read a few articles from people expressing their fear of buying Chinese electric cars, in case the Chinese government decides one day to introduce some line of evil code into their car. Today I think it is a bit of paranoia, but we also have to be clear that it can be a reality. And I don't know how that risk can be avoided.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The manufacturers of these cars can update the car's software via online or Wi-Fi, and users are completely in their hands. I don't know if it is true, but I have read that in China it is prohibited to park a Tesla car near military installations, since China is not sure what information those cars transmit to its headquarters in the USA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">There is no one innocent in this business, apart from users who think little and sometimes trust too much. Users are increasingly in the hands of manufacturers so that they can make money with the information they obtain from us.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">With these new electric cars we can do little other than be aware of the \u201cproblem\u201d, and adjust the car's privacy settings to limit the amount of data that is collected and shared.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">And as I said before, we have no idea what they get or what they do with that information. That is why it is essential that authorities and the automotive industry work together to develop stricter privacy and security standards for connected vehicles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">It is essential that we are aware that modern cars are full of high-tech cameras and sensors for the different safety systems and driving aids to work.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">But we must take into account this evolution is a double-edged sword, because it makes vehicles more vulnerable to cyber attacks, in addition to obtaining all types of user data.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la perspectiva de las agencias de inteligencia, estos coches, con sus numerosos sensores y c\u00e1maras,&nbsp;alguno los ha definido como \u201cm\u00e1quinas de esp\u00edar sobre cuatro ruedas\u00bb, pues los veh\u00edculos el\u00e9ctricos pueden filmar todo lo que ocurre a su alrededor mientras circulan por nuestras ciudades y luego&nbsp;transferir los datos a sus fabricantes, algunos de los cuales est\u00e1n en China.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">And the question that arises is: Is that what we want? Do we want our government to have eyes and ears on many of the cars that circulate through our cities? And what happens if that government is foreign, as may be the case with China?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The European Union has introduced a series of cybersecurity rules for new cars. Starting July 7, 2024, all new models sold in the region must comply with UN regulations R155 and R156.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R155 requires a management system from manufacturers, while R156 ensures that vehicle software updates are safer from cybersecurity threats.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">But there is no guarantee about the control of the data that car manufacturers obtain from us. And this is an urgent issue to resolve.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">We'll see how this matter evolves over time.<\/p>","protected":false},"excerpt":{"rendered":"<p>Views: 21 Los coches modernos, especialmente los el\u00e9ctricos, se han convertido en sistemas inform\u00e1ticos complejos sobre ruedas. Su sistema inform\u00e1tico controla todo el funcionamiento del veh\u00edculo, desde el motor y la transmisi\u00f3n hasta las funciones de infoentretenimiento y seguridad. Adem\u00e1s, recopilan una gran cantidad de datos sobre nosotros, nuestro entorno y nuestros h\u00e1bitos de conducci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[111,110,124,109],"tags":[],"class_list":["post-2860","post","type-post","status-publish","format-standard","hentry","category-autonomous-cars-vehicles","category-cars-vehicles","category-electric-cars","category-vehicles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los coches modernos son uno de los mayores riesgos para nuestra privacidad y nuestra seguridad - Desde la terraza de Amador<\/title>\n<meta name=\"description\" content=\"Los coches modernos, especialmente los el\u00e9ctricos, se han convertido en sistemas inform\u00e1ticos complejos sobre ruedas. Su sistema inform\u00e1tico controla todo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desdelaterrazadeamador.com\/en\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los coches modernos son uno de los mayores riesgos para nuestra privacidad y nuestra seguridad - Desde la terraza de Amador\" \/>\n<meta property=\"og:description\" content=\"Los coches modernos, especialmente los el\u00e9ctricos, se han convertido en sistemas inform\u00e1ticos complejos sobre ruedas. Su sistema inform\u00e1tico controla todo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desdelaterrazadeamador.com\/en\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\/\" \/>\n<meta property=\"og:site_name\" content=\"Desde la terraza de Amador\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-16T06:23:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-19T06:07:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2024\/05\/Coche-moderno-electrico.jpg\" \/>\n<meta name=\"author\" content=\"Amador Palacios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/edurneamaya\" \/>\n<meta name=\"twitter:site\" content=\"@edurneamaya\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amador Palacios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\\\/\"},\"author\":{\"name\":\"Amador Palacios\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"headline\":\"Los coches modernos son uno de los mayores riesgos para nuestra privacidad y nuestra seguridad\",\"datePublished\":\"2024-05-16T06:23:05+00:00\",\"dateModified\":\"2024-05-19T06:07:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\\\/\"},\"wordCount\":759,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"image\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Coche-moderno-electrico.jpg\",\"articleSection\":[\"Autonomous Cars\",\"Cars\",\"Electric cars\",\"Vehicles\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\\\/\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\\\/\",\"name\":\"Los coches modernos son uno de los mayores riesgos para nuestra privacidad y nuestra seguridad - Desde la terraza de Amador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Coche-moderno-electrico.jpg\",\"datePublished\":\"2024-05-16T06:23:05+00:00\",\"dateModified\":\"2024-05-19T06:07:38+00:00\",\"description\":\"Los coches modernos, especialmente los el\u00e9ctricos, se han convertido en sistemas inform\u00e1ticos complejos sobre ruedas. Su sistema inform\u00e1tico controla todo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Coche-moderno-electrico.jpg\",\"contentUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Coche-moderno-electrico.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los coches modernos son uno de los mayores riesgos para nuestra privacidad y nuestra seguridad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#website\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/\",\"name\":\"Desde la terraza de Amador\",\"description\":\"Reflexiones libres y honestas sobre temas de actualidad social y tecnol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\",\"name\":\"Amador Palacios\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"contentUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"width\":1265,\"height\":899,\"caption\":\"Amador Palacios\"},\"logo\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\"},\"description\":\"Reflexiones de Amador Palacios sobre temas de Actualidad Social y Tecnol\u00f3gica; otras opiniones diferentes a la m\u00eda son bienvenidas\",\"sameAs\":[\"http:\\\/\\\/desdelaterrazadeamador.com\",\"https:\\\/\\\/es.linkedin.com\\\/in\\\/amador-palacios-499532a\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/edurneamaya\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los coches modernos son uno de los mayores riesgos para nuestra privacidad y nuestra seguridad - Desde la terraza de Amador","description":"Los coches modernos, especialmente los el\u00e9ctricos, se han convertido en sistemas inform\u00e1ticos complejos sobre ruedas. Su sistema inform\u00e1tico controla todo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desdelaterrazadeamador.com\/en\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\/","og_locale":"en_US","og_type":"article","og_title":"Los coches modernos son uno de los mayores riesgos para nuestra privacidad y nuestra seguridad - Desde la terraza de Amador","og_description":"Los coches modernos, especialmente los el\u00e9ctricos, se han convertido en sistemas inform\u00e1ticos complejos sobre ruedas. Su sistema inform\u00e1tico controla todo","og_url":"https:\/\/desdelaterrazadeamador.com\/en\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\/","og_site_name":"Desde la terraza de Amador","article_published_time":"2024-05-16T06:23:05+00:00","article_modified_time":"2024-05-19T06:07:38+00:00","og_image":[{"url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2024\/05\/Coche-moderno-electrico.jpg","type":"","width":"","height":""}],"author":"Amador Palacios","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/edurneamaya","twitter_site":"@edurneamaya","twitter_misc":{"Written by":"Amador Palacios","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/desdelaterrazadeamador.com\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\/#article","isPartOf":{"@id":"https:\/\/desdelaterrazadeamador.com\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\/"},"author":{"name":"Amador Palacios","@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"headline":"Los coches modernos son uno de los mayores riesgos para nuestra privacidad y nuestra seguridad","datePublished":"2024-05-16T06:23:05+00:00","dateModified":"2024-05-19T06:07:38+00:00","mainEntityOfPage":{"@id":"https:\/\/desdelaterrazadeamador.com\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\/"},"wordCount":759,"commentCount":0,"publisher":{"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"image":{"@id":"https:\/\/desdelaterrazadeamador.com\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\/#primaryimage"},"thumbnailUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2024\/05\/Coche-moderno-electrico.jpg","articleSection":["Autonomous Cars","Cars","Electric cars","Vehicles"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/desdelaterrazadeamador.com\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/desdelaterrazadeamador.com\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\/","url":"https:\/\/desdelaterrazadeamador.com\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\/","name":"Los coches modernos son uno de los mayores riesgos para nuestra privacidad y nuestra seguridad - Desde la terraza de Amador","isPartOf":{"@id":"https:\/\/desdelaterrazadeamador.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/desdelaterrazadeamador.com\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\/#primaryimage"},"image":{"@id":"https:\/\/desdelaterrazadeamador.com\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\/#primaryimage"},"thumbnailUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2024\/05\/Coche-moderno-electrico.jpg","datePublished":"2024-05-16T06:23:05+00:00","dateModified":"2024-05-19T06:07:38+00:00","description":"Los coches modernos, especialmente los el\u00e9ctricos, se han convertido en sistemas inform\u00e1ticos complejos sobre ruedas. Su sistema inform\u00e1tico controla todo","breadcrumb":{"@id":"https:\/\/desdelaterrazadeamador.com\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desdelaterrazadeamador.com\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/desdelaterrazadeamador.com\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\/#primaryimage","url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2024\/05\/Coche-moderno-electrico.jpg","contentUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2024\/05\/Coche-moderno-electrico.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/desdelaterrazadeamador.com\/los-coches-modernos-son-uno-de-los-mayores-riesgos-para-nuestra-privacidad-y-nuestra-seguridad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/desdelaterrazadeamador.com\/"},{"@type":"ListItem","position":2,"name":"Los coches modernos son uno de los mayores riesgos para nuestra privacidad y nuestra seguridad"}]},{"@type":"WebSite","@id":"https:\/\/desdelaterrazadeamador.com\/#website","url":"https:\/\/desdelaterrazadeamador.com\/","name":"Desde la terraza de Amador","description":"Free and honest reflections on current social and technological issues","publisher":{"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desdelaterrazadeamador.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66","name":"Amador Palacios","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","contentUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","width":1265,"height":899,"caption":"Amador Palacios"},"logo":{"@id":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg"},"description":"Reflexiones de Amador Palacios sobre temas de Actualidad Social y Tecnol\u00f3gica; otras opiniones diferentes a la m\u00eda son bienvenidas","sameAs":["http:\/\/desdelaterrazadeamador.com","https:\/\/es.linkedin.com\/in\/amador-palacios-499532a","https:\/\/x.com\/https:\/\/twitter.com\/edurneamaya"]}]}},"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/2860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/comments?post=2860"}],"version-history":[{"count":1,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/2860\/revisions"}],"predecessor-version":[{"id":2862,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/2860\/revisions\/2862"}],"wp:attachment":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/media?parent=2860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/categories?post=2860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/tags?post=2860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}