{"id":2409,"date":"2023-11-29T08:42:26","date_gmt":"2023-11-29T07:42:26","guid":{"rendered":"https:\/\/desdelaterrazadeamador.com\/?p=2409"},"modified":"2023-12-02T08:20:43","modified_gmt":"2023-12-02T07:20:43","slug":"vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica","status":"publish","type":"post","link":"https:\/\/desdelaterrazadeamador.com\/en\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\/","title":{"rendered":"Is it worth banning short flights to fight the Climate Crisis?"},"content":{"rendered":"<p>Views: 20<\/p>\n<p class=\"wp-block-paragraph\">Aviation is one of the sectors with the greatest impact on climate change. Greenhouse gas (GHG) emissions from commercial aviation account for 2.5% of global emissions, and are expected to increase by 50% over the next 30 years.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">One of the measures that have been proposed to reduce aviation emissions is the ban on short flights. A short flight is defined as a flight of less than 500 kilometers, which is the distance that can be traveled by train in less than two and a half hours.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The ban on short flights has a direct impact on GHG emissions. A study by the European Environment Agency (EEA) estimates that banning short flights in Europe could reduce aviation emissions by 10%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">This has already begun to be applied in France and it seems that it will be done in other countries, but there are many people who are not happy with the measure. They argue that it can affect connectivity between cities, especially in regions with little rail infrastructure, and also that it can increase the cost of travel, since trains are usually more expensive than planes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">But this has a catch, since planes are cheaper than trains due to the subsidies applied to air transport. Which doesn't make much sense, especially when there are much less polluting transportation alternatives, as is the case with the train.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"225\" src=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2023\/11\/Avion-con-personas.jpg\" alt=\"\" class=\"wp-image-2410\" style=\"width:510px;height:auto\" srcset=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2023\/11\/Avion-con-personas.jpg 400w, https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2023\/11\/Avion-con-personas-300x169.jpg 300w, https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2023\/11\/Avion-con-personas-18x10.jpg 18w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">I think the most important step is for us citizens to realize once and for all that the Climate Crisis is one of the biggest problems we have, if not the biggest in the medium-long term, and that we must act accordingly.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The most important thing is to modify our customs, and be aware that we have to \u201cgive up\u201d some of our current privileges to leave our descendants a more sustainable climate environment. With the ultimate goal of making it completely sustainable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">And we don't have to let them fool us, flights, and especially those of large airplanes, are very far from being non-polluting, since there is no real alternative. Those who talk about the use of SAF fuels do not say that there will not be that type of fuel for all the needs of current and future flights. It is a half-truth, or what is the same: a deception. Pure and simple \u201cgreen-washing\u201d to deceive people.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pleasure flights, which are the majority, like cruise trips, and many others, are recreational activities that we carry out by contaminating our environment, and that we should think a little about before doing them. We can entertain ourselves with other activities and in other less distant places.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">We can live well in a different way and pollute much less. We just have to be aware of the challenge before us, and be willing to \u201close\u201d some of the benefits we enjoy, to leave a better future for our descendants.<\/p>","protected":false},"excerpt":{"rendered":"<p>Views: 20 La aviaci\u00f3n es uno de los sectores con mayor impacto en el cambio clim\u00e1tico. Las emisiones de gases de efecto invernadero (GEI) de la aviaci\u00f3n comercial representan el 2,5% de las emisiones globales, y se espera que aumenten en un 50% en los pr\u00f3ximos 30 a\u00f1os. Una de las medidas que se han [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":718,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[121,112,155],"tags":[],"class_list":["post-2409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-airplanes","category-climatic-change","category-transportation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bf Vale la pena prohibir los vuelos cortos para luchar contra la Crisis Clim\u00e1tica ? - Desde la terraza de Amador<\/title>\n<meta name=\"description\" content=\"La aviaci\u00f3n es uno de los sectores con mayor impacto en el cambio clim\u00e1tico. Las emisiones de gases de efecto invernadero (GEI) de la aviaci\u00f3n comercial\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desdelaterrazadeamador.com\/en\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bf Vale la pena prohibir los vuelos cortos para luchar contra la Crisis Clim\u00e1tica ? - Desde la terraza de Amador\" \/>\n<meta property=\"og:description\" content=\"La aviaci\u00f3n es uno de los sectores con mayor impacto en el cambio clim\u00e1tico. Las emisiones de gases de efecto invernadero (GEI) de la aviaci\u00f3n comercial\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desdelaterrazadeamador.com\/en\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\/\" \/>\n<meta property=\"og:site_name\" content=\"Desde la terraza de Amador\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-29T07:42:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-02T07:20:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/04\/Avion-MODELO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Amador Palacios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/edurneamaya\" \/>\n<meta name=\"twitter:site\" content=\"@edurneamaya\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amador Palacios\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\\\/\"},\"author\":{\"name\":\"Amador Palacios\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"headline\":\"\u00bf Vale la pena prohibir los vuelos cortos para luchar contra la Crisis Clim\u00e1tica ?\",\"datePublished\":\"2023-11-29T07:42:26+00:00\",\"dateModified\":\"2023-12-02T07:20:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\\\/\"},\"wordCount\":547,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"image\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Avion-MODELO.jpg\",\"articleSection\":[\"Airplanes\",\"Climatic Change\",\"Transportation\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/desdelaterrazadeamador.com\\\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\\\/\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\\\/\",\"name\":\"\u00bf Vale la pena prohibir los vuelos cortos para luchar contra la Crisis Clim\u00e1tica ? - Desde la terraza de Amador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Avion-MODELO.jpg\",\"datePublished\":\"2023-11-29T07:42:26+00:00\",\"dateModified\":\"2023-12-02T07:20:43+00:00\",\"description\":\"La aviaci\u00f3n es uno de los sectores con mayor impacto en el cambio clim\u00e1tico. Las emisiones de gases de efecto invernadero (GEI) de la aviaci\u00f3n comercial\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desdelaterrazadeamador.com\\\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Avion-MODELO.jpg\",\"contentUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Avion-MODELO.jpg\",\"width\":640,\"height\":426},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bf Vale la pena prohibir los vuelos cortos para luchar contra la Crisis Clim\u00e1tica ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#website\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/\",\"name\":\"Desde la terraza de Amador\",\"description\":\"Reflexiones libres y honestas sobre temas de actualidad social y tecnol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\",\"name\":\"Amador Palacios\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"contentUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"width\":1265,\"height\":899,\"caption\":\"Amador Palacios\"},\"logo\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\"},\"description\":\"Reflexiones de Amador Palacios sobre temas de Actualidad Social y Tecnol\u00f3gica; otras opiniones diferentes a la m\u00eda son bienvenidas\",\"sameAs\":[\"http:\\\/\\\/desdelaterrazadeamador.com\",\"https:\\\/\\\/es.linkedin.com\\\/in\\\/amador-palacios-499532a\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/edurneamaya\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bf Vale la pena prohibir los vuelos cortos para luchar contra la Crisis Clim\u00e1tica ? - Desde la terraza de Amador","description":"La aviaci\u00f3n es uno de los sectores con mayor impacto en el cambio clim\u00e1tico. Las emisiones de gases de efecto invernadero (GEI) de la aviaci\u00f3n comercial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desdelaterrazadeamador.com\/en\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\/","og_locale":"en_US","og_type":"article","og_title":"\u00bf Vale la pena prohibir los vuelos cortos para luchar contra la Crisis Clim\u00e1tica ? - Desde la terraza de Amador","og_description":"La aviaci\u00f3n es uno de los sectores con mayor impacto en el cambio clim\u00e1tico. Las emisiones de gases de efecto invernadero (GEI) de la aviaci\u00f3n comercial","og_url":"https:\/\/desdelaterrazadeamador.com\/en\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\/","og_site_name":"Desde la terraza de Amador","article_published_time":"2023-11-29T07:42:26+00:00","article_modified_time":"2023-12-02T07:20:43+00:00","og_image":[{"width":640,"height":426,"url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/04\/Avion-MODELO.jpg","type":"image\/jpeg"}],"author":"Amador Palacios","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/edurneamaya","twitter_site":"@edurneamaya","twitter_misc":{"Written by":"Amador Palacios"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/desdelaterrazadeamador.com\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\/#article","isPartOf":{"@id":"https:\/\/desdelaterrazadeamador.com\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\/"},"author":{"name":"Amador Palacios","@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"headline":"\u00bf Vale la pena prohibir los vuelos cortos para luchar contra la Crisis Clim\u00e1tica ?","datePublished":"2023-11-29T07:42:26+00:00","dateModified":"2023-12-02T07:20:43+00:00","mainEntityOfPage":{"@id":"https:\/\/desdelaterrazadeamador.com\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\/"},"wordCount":547,"commentCount":0,"publisher":{"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"image":{"@id":"https:\/\/desdelaterrazadeamador.com\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\/#primaryimage"},"thumbnailUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/04\/Avion-MODELO.jpg","articleSection":["Airplanes","Climatic Change","Transportation"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/desdelaterrazadeamador.com\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/desdelaterrazadeamador.com\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\/","url":"https:\/\/desdelaterrazadeamador.com\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\/","name":"\u00bf Vale la pena prohibir los vuelos cortos para luchar contra la Crisis Clim\u00e1tica ? - Desde la terraza de Amador","isPartOf":{"@id":"https:\/\/desdelaterrazadeamador.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/desdelaterrazadeamador.com\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\/#primaryimage"},"image":{"@id":"https:\/\/desdelaterrazadeamador.com\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\/#primaryimage"},"thumbnailUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/04\/Avion-MODELO.jpg","datePublished":"2023-11-29T07:42:26+00:00","dateModified":"2023-12-02T07:20:43+00:00","description":"La aviaci\u00f3n es uno de los sectores con mayor impacto en el cambio clim\u00e1tico. Las emisiones de gases de efecto invernadero (GEI) de la aviaci\u00f3n comercial","breadcrumb":{"@id":"https:\/\/desdelaterrazadeamador.com\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desdelaterrazadeamador.com\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/desdelaterrazadeamador.com\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\/#primaryimage","url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/04\/Avion-MODELO.jpg","contentUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/04\/Avion-MODELO.jpg","width":640,"height":426},{"@type":"BreadcrumbList","@id":"https:\/\/desdelaterrazadeamador.com\/vale-la-pena-prohibir-los-vuelos-cortos-para-luchar-contra-la-crisis-climatica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/desdelaterrazadeamador.com\/"},{"@type":"ListItem","position":2,"name":"\u00bf Vale la pena prohibir los vuelos cortos para luchar contra la Crisis Clim\u00e1tica ?"}]},{"@type":"WebSite","@id":"https:\/\/desdelaterrazadeamador.com\/#website","url":"https:\/\/desdelaterrazadeamador.com\/","name":"Desde la terraza de Amador","description":"Free and honest reflections on current social and technological issues","publisher":{"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desdelaterrazadeamador.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66","name":"Amador Palacios","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","contentUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","width":1265,"height":899,"caption":"Amador Palacios"},"logo":{"@id":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg"},"description":"Reflexiones de Amador Palacios sobre temas de Actualidad Social y Tecnol\u00f3gica; otras opiniones diferentes a la m\u00eda son bienvenidas","sameAs":["http:\/\/desdelaterrazadeamador.com","https:\/\/es.linkedin.com\/in\/amador-palacios-499532a","https:\/\/x.com\/https:\/\/twitter.com\/edurneamaya"]}]}},"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/2409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/comments?post=2409"}],"version-history":[{"count":1,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/2409\/revisions"}],"predecessor-version":[{"id":2411,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/2409\/revisions\/2411"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/media\/718"}],"wp:attachment":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/media?parent=2409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/categories?post=2409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/tags?post=2409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}