{"id":2309,"date":"2023-10-24T08:49:09","date_gmt":"2023-10-24T06:49:09","guid":{"rendered":"https:\/\/desdelaterrazadeamador.com\/?p=2309"},"modified":"2023-10-29T07:51:34","modified_gmt":"2023-10-29T06:51:34","slug":"seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica","status":"publish","type":"post","link":"https:\/\/desdelaterrazadeamador.com\/en\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\/","title":{"rendered":"Six young people bring more than 32 European countries to trial for the Climate Crisis"},"content":{"rendered":"<p>Views: 17<\/p>\n<p class=\"wp-block-paragraph\">Some will think that this trial is a publicity act and that it will have no further consequences. I agree that it is an advertising act, but something must be done to raise awareness among citizens of the enormous problem we face, and that will fully affect future generations.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I don't know about the consequences, and it depends on how much the message these young people are trying to convey reaches society. And I hope it has success catching on.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">On September 27, 2023, six young Portuguese men (aged between 11 and 24) took 32 European countries to trial before the European Court of Human Rights (ECHR). The lawsuit, which is the first of its kind in the world, alleges that the defendant governments are failing to meet their human rights obligations by not doing enough to protect young people from climate change.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"168\" src=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2023\/10\/Clima-MODELO.jpg\" alt=\"\" class=\"wp-image-2310\" style=\"width:416px;height:auto\" srcset=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2023\/10\/Clima-MODELO.jpg 300w, https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2023\/10\/Clima-MODELO-18x10.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">In their lawsuit, the young Portuguese argue that climate change is violating their rights to life, health, a healthy environment and education. They point out that the effects of climate change are already being felt around the world, in the form of heat waves, droughts, floods and extreme weather events. These phenomena are having a devastating impact on the lives of young people, who are deprived of their future and their opportunities.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The plaintiffs ask the ECHR to force the accused governments to take more ambitious measures to reduce greenhouse gas emissions. They also ask that they be compensated for the damage they have already suffered.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The outcome of the trial could have a significant impact on the fight against climate change. If the ECHR rules in favor of the young Portuguese, it could force the accused governments to take more ambitious measures to reduce greenhouse gas emissions. Which would be a real shame for the politicians who have been in power in recent years.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">And in addition, this trial could also set a precedent for other similar cases that are being processed around the world. In recent years, climate lawsuits have been filed in several countries, including the United States, Australia and Brazil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The participation of young people in this issue is essential, since they are going to be the most affected by the consequences of Climate Change, but I think that we should all raise awareness about the issue, since most of us have children and grandchildren, and we must leave them an environment of life equal to or better than what we receive.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I expect almost nothing from this type of trial, but if it helps that more people get involved in solving the biggest problem the world faces today, it is welcome.<\/p>","protected":false},"excerpt":{"rendered":"<p>Views: 17 Algunos pensar\u00e1n que este juicio es un acto publicitario y que no tendr\u00e1 posteriores consecuencias. Estoy de acuerdo con que es un acto publicitario, pero algo hay que hacer para sensibilizar a la ciudadan\u00eda del enorme problema que tenemos enfrente, y que va a afectar de lleno a las generaciones futuras. Lo de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":460,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[112,113],"tags":[],"class_list":["post-2309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-climatic-change","category-pollution-climatic-change"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Seis j\u00f3venes llevan a m\u00e1s de 32 pa\u00edses europeos ante el juez por la Crisis Clim\u00e1tica - Desde la terraza de Amador<\/title>\n<meta name=\"description\" content=\"Algunos pensar\u00e1n que este juicio es un acto publicitario y que no tendr\u00e1 posteriores consecuencias. Estoy de acuerdo con que es un acto publicitario, pero\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desdelaterrazadeamador.com\/en\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seis j\u00f3venes llevan a m\u00e1s de 32 pa\u00edses europeos ante el juez por la Crisis Clim\u00e1tica - Desde la terraza de Amador\" \/>\n<meta property=\"og:description\" content=\"Algunos pensar\u00e1n que este juicio es un acto publicitario y que no tendr\u00e1 posteriores consecuencias. Estoy de acuerdo con que es un acto publicitario, pero\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desdelaterrazadeamador.com\/en\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\/\" \/>\n<meta property=\"og:site_name\" content=\"Desde la terraza de Amador\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-24T06:49:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-29T06:51:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Cambio-climatico-MODELO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"452\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Amador Palacios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/edurneamaya\" \/>\n<meta name=\"twitter:site\" content=\"@edurneamaya\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amador Palacios\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\\\/\"},\"author\":{\"name\":\"Amador Palacios\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"headline\":\"Seis j\u00f3venes llevan a m\u00e1s de 32 pa\u00edses europeos ante el juez por la Crisis Clim\u00e1tica\",\"datePublished\":\"2023-10-24T06:49:09+00:00\",\"dateModified\":\"2023-10-29T06:51:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\\\/\"},\"wordCount\":521,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"image\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Cambio-climatico-MODELO.jpg\",\"articleSection\":[\"Climatic Change\",\"Pollution\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\\\/\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\\\/\",\"name\":\"Seis j\u00f3venes llevan a m\u00e1s de 32 pa\u00edses europeos ante el juez por la Crisis Clim\u00e1tica - Desde la terraza de Amador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Cambio-climatico-MODELO.jpg\",\"datePublished\":\"2023-10-24T06:49:09+00:00\",\"dateModified\":\"2023-10-29T06:51:34+00:00\",\"description\":\"Algunos pensar\u00e1n que este juicio es un acto publicitario y que no tendr\u00e1 posteriores consecuencias. Estoy de acuerdo con que es un acto publicitario, pero\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Cambio-climatico-MODELO.jpg\",\"contentUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Cambio-climatico-MODELO.jpg\",\"width\":640,\"height\":452},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seis j\u00f3venes llevan a m\u00e1s de 32 pa\u00edses europeos ante el juez por la Crisis Clim\u00e1tica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#website\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/\",\"name\":\"Desde la terraza de Amador\",\"description\":\"Reflexiones libres y honestas sobre temas de actualidad social y tecnol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\",\"name\":\"Amador Palacios\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"contentUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"width\":1265,\"height\":899,\"caption\":\"Amador Palacios\"},\"logo\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\"},\"description\":\"Reflexiones de Amador Palacios sobre temas de Actualidad Social y Tecnol\u00f3gica; otras opiniones diferentes a la m\u00eda son bienvenidas\",\"sameAs\":[\"http:\\\/\\\/desdelaterrazadeamador.com\",\"https:\\\/\\\/es.linkedin.com\\\/in\\\/amador-palacios-499532a\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/edurneamaya\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seis j\u00f3venes llevan a m\u00e1s de 32 pa\u00edses europeos ante el juez por la Crisis Clim\u00e1tica - Desde la terraza de Amador","description":"Algunos pensar\u00e1n que este juicio es un acto publicitario y que no tendr\u00e1 posteriores consecuencias. Estoy de acuerdo con que es un acto publicitario, pero","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desdelaterrazadeamador.com\/en\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\/","og_locale":"en_US","og_type":"article","og_title":"Seis j\u00f3venes llevan a m\u00e1s de 32 pa\u00edses europeos ante el juez por la Crisis Clim\u00e1tica - Desde la terraza de Amador","og_description":"Algunos pensar\u00e1n que este juicio es un acto publicitario y que no tendr\u00e1 posteriores consecuencias. Estoy de acuerdo con que es un acto publicitario, pero","og_url":"https:\/\/desdelaterrazadeamador.com\/en\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\/","og_site_name":"Desde la terraza de Amador","article_published_time":"2023-10-24T06:49:09+00:00","article_modified_time":"2023-10-29T06:51:34+00:00","og_image":[{"width":640,"height":452,"url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Cambio-climatico-MODELO.jpg","type":"image\/jpeg"}],"author":"Amador Palacios","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/edurneamaya","twitter_site":"@edurneamaya","twitter_misc":{"Written by":"Amador Palacios"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/desdelaterrazadeamador.com\/en\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\/#article","isPartOf":{"@id":"https:\/\/desdelaterrazadeamador.com\/en\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\/"},"author":{"name":"Amador Palacios","@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"headline":"Seis j\u00f3venes llevan a m\u00e1s de 32 pa\u00edses europeos ante el juez por la Crisis Clim\u00e1tica","datePublished":"2023-10-24T06:49:09+00:00","dateModified":"2023-10-29T06:51:34+00:00","mainEntityOfPage":{"@id":"https:\/\/desdelaterrazadeamador.com\/en\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\/"},"wordCount":521,"commentCount":0,"publisher":{"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"image":{"@id":"https:\/\/desdelaterrazadeamador.com\/en\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\/#primaryimage"},"thumbnailUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Cambio-climatico-MODELO.jpg","articleSection":["Climatic Change","Pollution"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/desdelaterrazadeamador.com\/en\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/desdelaterrazadeamador.com\/en\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\/","url":"https:\/\/desdelaterrazadeamador.com\/en\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\/","name":"Seis j\u00f3venes llevan a m\u00e1s de 32 pa\u00edses europeos ante el juez por la Crisis Clim\u00e1tica - Desde la terraza de Amador","isPartOf":{"@id":"https:\/\/desdelaterrazadeamador.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/desdelaterrazadeamador.com\/en\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\/#primaryimage"},"image":{"@id":"https:\/\/desdelaterrazadeamador.com\/en\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\/#primaryimage"},"thumbnailUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Cambio-climatico-MODELO.jpg","datePublished":"2023-10-24T06:49:09+00:00","dateModified":"2023-10-29T06:51:34+00:00","description":"Algunos pensar\u00e1n que este juicio es un acto publicitario y que no tendr\u00e1 posteriores consecuencias. Estoy de acuerdo con que es un acto publicitario, pero","breadcrumb":{"@id":"https:\/\/desdelaterrazadeamador.com\/en\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desdelaterrazadeamador.com\/en\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/desdelaterrazadeamador.com\/en\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\/#primaryimage","url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Cambio-climatico-MODELO.jpg","contentUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Cambio-climatico-MODELO.jpg","width":640,"height":452},{"@type":"BreadcrumbList","@id":"https:\/\/desdelaterrazadeamador.com\/en\/seis-jovenes-llevan-a-mas-de-32-paises-europeos-ante-el-juez-por-la-crisis-climatica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/desdelaterrazadeamador.com\/"},{"@type":"ListItem","position":2,"name":"Seis j\u00f3venes llevan a m\u00e1s de 32 pa\u00edses europeos ante el juez por la Crisis Clim\u00e1tica"}]},{"@type":"WebSite","@id":"https:\/\/desdelaterrazadeamador.com\/#website","url":"https:\/\/desdelaterrazadeamador.com\/","name":"Desde la terraza de Amador","description":"Free and honest reflections on current social and technological issues","publisher":{"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desdelaterrazadeamador.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66","name":"Amador Palacios","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","contentUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","width":1265,"height":899,"caption":"Amador Palacios"},"logo":{"@id":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg"},"description":"Reflexiones de Amador Palacios sobre temas de Actualidad Social y Tecnol\u00f3gica; otras opiniones diferentes a la m\u00eda son bienvenidas","sameAs":["http:\/\/desdelaterrazadeamador.com","https:\/\/es.linkedin.com\/in\/amador-palacios-499532a","https:\/\/x.com\/https:\/\/twitter.com\/edurneamaya"]}]}},"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/2309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/comments?post=2309"}],"version-history":[{"count":1,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/2309\/revisions"}],"predecessor-version":[{"id":2311,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/2309\/revisions\/2311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/media\/460"}],"wp:attachment":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/media?parent=2309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/categories?post=2309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/tags?post=2309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}