{"id":2231,"date":"2023-09-25T08:54:11","date_gmt":"2023-09-25T06:54:11","guid":{"rendered":"https:\/\/desdelaterrazadeamador.com\/?p=2231"},"modified":"2023-09-30T15:41:48","modified_gmt":"2023-09-30T13:41:48","slug":"los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano","status":"publish","type":"post","link":"https:\/\/desdelaterrazadeamador.com\/en\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\/","title":{"rendered":"Are hands-free driving systems safer than driving with a human driver?"},"content":{"rendered":"<p>Views: 18<\/p>\n<p class=\"wp-block-paragraph\">It is clear that hands-free driving systems are offered in almost all new models, and especially if it is a high-end car, but in general car manufacturers are very careful to insist that the driver must not take their eyes off what happens on the road, and that you are still responsible for the safety of the vehicle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">But one thing is what is said, and another, sometimes quite different, is what is done. Because as these systems increase their capabilities, drivers trust them more and end up paying less attention to what happens on the road. And from there to the accident there is only one step.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I read that General Motors is going to run an information campaign about its hands-free driving system called Super Cruise, to explain what it does and what it doesn't do, and to insist to potential customers that it is not an autonomous driving system. And insisting that drivers are the only ones responsible for the safety of their car.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2023\/09\/Conduccion-Super-Cruise.jpg\" alt=\"\" class=\"wp-image-2232\" style=\"width:539px;height:auto\" srcset=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2023\/09\/Conduccion-Super-Cruise.jpg 400w, https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2023\/09\/Conduccion-Super-Cruise-300x200.jpg 300w, https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2023\/09\/Conduccion-Super-Cruise-18x12.jpg 18w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">I think it is a very interesting action to inform users of what they have in their hands, and especially after so many comments tending to misinform, such as those made by Tesla with its Full Self-Driving system, which is not at all Full Driving and that has already produced 17 deaths. I don't understand how the authorities allow these deceptions.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Make no mistake, these systems are \"aids\" to driving that can become a \"risk\" if drivers rely too much on them and stop paying attention to what is happening on the road. Which is very normal after a certain time of using them.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">And even if they use them well, over time people become more trusting, and when at a given moment the driver has to take over driving, it is very possible that he takes longer than he should to do so and suffers an accident.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I am not very clear where is the midpoint of the use of these \"improvements\" to driving. On highways there are fewer incidents and they may be more useful, and in cities the possible incidents are higher and they may be less useful.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Each driver should be as well informed as possible, and will have to see how he applies these aids to his driving. And for this reason I applaud GM's initiative to inform users, as it is a sign of responsibility.<\/p>","protected":false},"excerpt":{"rendered":"<p>Views: 18 Est\u00e1 claro que los sistemas de conducci\u00f3n manos libres se ofrecen en casi todos los nuevos modelos, y en especial si es un coche de alta gama, pero en general los fabricantes de coches tienen mucho cuidado en insistir que el conductor no debe de quitar los ojos de lo que sucede en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1141,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[111,127],"tags":[],"class_list":["post-2231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autonomous-cars-vehicles","category-autonomous-vehicles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bf Los sistemas de conducci\u00f3n manos libres son m\u00e1s seguros que la conducci\u00f3n de un conductor humano\u00a0 ? - Desde la terraza de Amador<\/title>\n<meta name=\"description\" content=\"Est\u00e1 claro que los sistemas de conducci\u00f3n manos libres se ofrecen en casi todos los nuevos modelos, y en especial si es un coche de alta gama, pero en\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desdelaterrazadeamador.com\/en\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bf Los sistemas de conducci\u00f3n manos libres son m\u00e1s seguros que la conducci\u00f3n de un conductor humano\u00a0 ? - Desde la terraza de Amador\" \/>\n<meta property=\"og:description\" content=\"Est\u00e1 claro que los sistemas de conducci\u00f3n manos libres se ofrecen en casi todos los nuevos modelos, y en especial si es un coche de alta gama, pero en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desdelaterrazadeamador.com\/en\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\/\" \/>\n<meta property=\"og:site_name\" content=\"Desde la terraza de Amador\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-25T06:54:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-30T13:41:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/09\/Coche-autonomo-MODELO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"237\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Amador Palacios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/edurneamaya\" \/>\n<meta name=\"twitter:site\" content=\"@edurneamaya\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amador Palacios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\\\/\"},\"author\":{\"name\":\"Amador Palacios\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"headline\":\"\u00bf Los sistemas de conducci\u00f3n manos libres son m\u00e1s seguros que la conducci\u00f3n de un conductor humano\u00a0 ?\",\"datePublished\":\"2023-09-25T06:54:11+00:00\",\"dateModified\":\"2023-09-30T13:41:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\\\/\"},\"wordCount\":463,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"image\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Coche-autonomo-MODELO.jpg\",\"articleSection\":[\"Autonomous Cars\",\"Autonomous Vehicles\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\\\/\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\\\/\",\"name\":\"\u00bf Los sistemas de conducci\u00f3n manos libres son m\u00e1s seguros que la conducci\u00f3n de un conductor humano\u00a0 ? - Desde la terraza de Amador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Coche-autonomo-MODELO.jpg\",\"datePublished\":\"2023-09-25T06:54:11+00:00\",\"dateModified\":\"2023-09-30T13:41:48+00:00\",\"description\":\"Est\u00e1 claro que los sistemas de conducci\u00f3n manos libres se ofrecen en casi todos los nuevos modelos, y en especial si es un coche de alta gama, pero en\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Coche-autonomo-MODELO.jpg\",\"contentUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Coche-autonomo-MODELO.jpg\",\"width\":400,\"height\":237},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bf Los sistemas de conducci\u00f3n manos libres son m\u00e1s seguros que la conducci\u00f3n de un conductor humano\u00a0 ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#website\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/\",\"name\":\"Desde la terraza de Amador\",\"description\":\"Reflexiones libres y honestas sobre temas de actualidad social y tecnol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\",\"name\":\"Amador Palacios\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"contentUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"width\":1265,\"height\":899,\"caption\":\"Amador Palacios\"},\"logo\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\"},\"description\":\"Reflexiones de Amador Palacios sobre temas de Actualidad Social y Tecnol\u00f3gica; otras opiniones diferentes a la m\u00eda son bienvenidas\",\"sameAs\":[\"http:\\\/\\\/desdelaterrazadeamador.com\",\"https:\\\/\\\/es.linkedin.com\\\/in\\\/amador-palacios-499532a\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/edurneamaya\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bf Los sistemas de conducci\u00f3n manos libres son m\u00e1s seguros que la conducci\u00f3n de un conductor humano\u00a0 ? - Desde la terraza de Amador","description":"Est\u00e1 claro que los sistemas de conducci\u00f3n manos libres se ofrecen en casi todos los nuevos modelos, y en especial si es un coche de alta gama, pero en","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desdelaterrazadeamador.com\/en\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\/","og_locale":"en_US","og_type":"article","og_title":"\u00bf Los sistemas de conducci\u00f3n manos libres son m\u00e1s seguros que la conducci\u00f3n de un conductor humano\u00a0 ? - Desde la terraza de Amador","og_description":"Est\u00e1 claro que los sistemas de conducci\u00f3n manos libres se ofrecen en casi todos los nuevos modelos, y en especial si es un coche de alta gama, pero en","og_url":"https:\/\/desdelaterrazadeamador.com\/en\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\/","og_site_name":"Desde la terraza de Amador","article_published_time":"2023-09-25T06:54:11+00:00","article_modified_time":"2023-09-30T13:41:48+00:00","og_image":[{"width":400,"height":237,"url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/09\/Coche-autonomo-MODELO.jpg","type":"image\/jpeg"}],"author":"Amador Palacios","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/edurneamaya","twitter_site":"@edurneamaya","twitter_misc":{"Written by":"Amador Palacios","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/desdelaterrazadeamador.com\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\/#article","isPartOf":{"@id":"https:\/\/desdelaterrazadeamador.com\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\/"},"author":{"name":"Amador Palacios","@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"headline":"\u00bf Los sistemas de conducci\u00f3n manos libres son m\u00e1s seguros que la conducci\u00f3n de un conductor humano\u00a0 ?","datePublished":"2023-09-25T06:54:11+00:00","dateModified":"2023-09-30T13:41:48+00:00","mainEntityOfPage":{"@id":"https:\/\/desdelaterrazadeamador.com\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\/"},"wordCount":463,"commentCount":0,"publisher":{"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"image":{"@id":"https:\/\/desdelaterrazadeamador.com\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\/#primaryimage"},"thumbnailUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/09\/Coche-autonomo-MODELO.jpg","articleSection":["Autonomous Cars","Autonomous Vehicles"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/desdelaterrazadeamador.com\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/desdelaterrazadeamador.com\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\/","url":"https:\/\/desdelaterrazadeamador.com\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\/","name":"\u00bf Los sistemas de conducci\u00f3n manos libres son m\u00e1s seguros que la conducci\u00f3n de un conductor humano\u00a0 ? - Desde la terraza de Amador","isPartOf":{"@id":"https:\/\/desdelaterrazadeamador.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/desdelaterrazadeamador.com\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\/#primaryimage"},"image":{"@id":"https:\/\/desdelaterrazadeamador.com\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\/#primaryimage"},"thumbnailUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/09\/Coche-autonomo-MODELO.jpg","datePublished":"2023-09-25T06:54:11+00:00","dateModified":"2023-09-30T13:41:48+00:00","description":"Est\u00e1 claro que los sistemas de conducci\u00f3n manos libres se ofrecen en casi todos los nuevos modelos, y en especial si es un coche de alta gama, pero en","breadcrumb":{"@id":"https:\/\/desdelaterrazadeamador.com\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desdelaterrazadeamador.com\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/desdelaterrazadeamador.com\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\/#primaryimage","url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/09\/Coche-autonomo-MODELO.jpg","contentUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/09\/Coche-autonomo-MODELO.jpg","width":400,"height":237},{"@type":"BreadcrumbList","@id":"https:\/\/desdelaterrazadeamador.com\/los-sistemas-de-conduccion-manos-libres-son-mas-seguros-que-la-conduccion-de-un-conductor-humano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/desdelaterrazadeamador.com\/"},{"@type":"ListItem","position":2,"name":"\u00bf Los sistemas de conducci\u00f3n manos libres son m\u00e1s seguros que la conducci\u00f3n de un conductor humano\u00a0 ?"}]},{"@type":"WebSite","@id":"https:\/\/desdelaterrazadeamador.com\/#website","url":"https:\/\/desdelaterrazadeamador.com\/","name":"Desde la terraza de Amador","description":"Free and honest reflections on current social and technological issues","publisher":{"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desdelaterrazadeamador.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66","name":"Amador Palacios","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","contentUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","width":1265,"height":899,"caption":"Amador Palacios"},"logo":{"@id":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg"},"description":"Reflexiones de Amador Palacios sobre temas de Actualidad Social y Tecnol\u00f3gica; otras opiniones diferentes a la m\u00eda son bienvenidas","sameAs":["http:\/\/desdelaterrazadeamador.com","https:\/\/es.linkedin.com\/in\/amador-palacios-499532a","https:\/\/x.com\/https:\/\/twitter.com\/edurneamaya"]}]}},"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/2231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/comments?post=2231"}],"version-history":[{"count":1,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/2231\/revisions"}],"predecessor-version":[{"id":2233,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/2231\/revisions\/2233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/media\/1141"}],"wp:attachment":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/media?parent=2231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/categories?post=2231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/tags?post=2231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}