{"id":1892,"date":"2023-05-25T08:43:42","date_gmt":"2023-05-25T06:43:42","guid":{"rendered":"https:\/\/desdelaterrazadeamador.com\/?p=1892"},"modified":"2023-06-08T19:23:19","modified_gmt":"2023-06-08T17:23:19","slug":"energia-electrica-por-gravedad","status":"publish","type":"post","link":"https:\/\/desdelaterrazadeamador.com\/en\/energia-electrica-por-gravedad\/","title":{"rendered":"Electric power by gravity"},"content":{"rendered":"<p>Views: 24<\/p>\n<p class=\"wp-block-paragraph\">It is known that the biggest \"problem\" of solar and wind energy is the intermittency of its supply, and that when there is no sun or wind, the electrical energy that the system needs must be provided by other means.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">On the other hand, these energies have the great advantage of being cheap and their price continues to decrease more each day. In the last decade alone, the price of solar energy has decreased by more than 80%, and that of wind energy by more than 60%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">It is therefore not surprising that more wind and solar parks are installed every day. But if we want to have sustainable electrical energy all the time, we must have sustainable alternatives for when there is no sun and there is no wind. It can be summed up by saying that without sustainable energy storage we will not be able to have a sustainable energy system.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">And this is what various companies are doing. Some time ago I commented on the case of a new company that was doing tests in Switzerland by placing weights on a crane, to obtain electrical energy at the time these weights were lowered. A seemingly simple way to take advantage of gravity to get energy.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I have recently read that this company (Energy Vault) has continued to work and is already carrying out two industrial projects, one in China and one in Texas. In the photo you can see the construction of one of them.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2023\/05\/Energia-por-gravedad.jpg\" alt=\"\" class=\"wp-image-1893\" width=\"583\" height=\"328\" srcset=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2023\/05\/Energia-por-gravedad.jpg 450w, https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2023\/05\/Energia-por-gravedad-300x169.jpg 300w, https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2023\/05\/Energia-por-gravedad-18x10.jpg 18w\" sizes=\"auto, (max-width: 583px) 100vw, 583px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">In these plants they will use blocks of 3.5 by 2.7 by 1.3 meters built with a special polymer + earth + water that weigh 24 tons each. When there is an excess of solar or wind energy, the blocks are raised with that excess energy, and stored in the upper levels of the buildings. And when it is necessary to recover energy, the blocks are lowered at a speed of 1.9 m\/s, generating an energy of the order of 1 Mw. each.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Although the principle of operation is simple, the management of the entire system is not simple at all, and there are thousands of blocks to manage.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The plant being built in China is going to be 122 meters high and will supply 100 MWh of energy, and the one being built in Texas is smaller and is expected to provide 36 MWh.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">There are other companies that are using similar technology (such as Gravitricity in the UK) and it would not be strange for new ones to appear, since the field of action is enormous. Many means of energy back-up are required to be able to achieve sustainable energy systems.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The challenge ahead of us is so enormous that almost all options are good if they help achieve it.<\/p>","protected":false},"excerpt":{"rendered":"<p>Views: 24 Se sabe que el mayor \u201cproblema\u201d de las energ\u00edas solar y e\u00f3lica es la intermitencia de su suministro, y que cuando no hay sol o viento la energ\u00eda el\u00e9ctrica que necesita el sistema debe de ser aportada por otros medios Por otra parte, estas energ\u00edas tienen la gran ventaja de ser baratas y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":439,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[134],"tags":[],"class_list":["post-1892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sustainable-energy"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Energ\u00eda el\u00e9ctrica por gravedad - Desde la terraza de Amador<\/title>\n<meta name=\"description\" content=\"Se sabe que el mayor \u201cproblema\u201d de las energ\u00edas solar y e\u00f3lica es la intermitencia de su suministro, y que cuando no hay sol o viento la energ\u00eda el\u00e9ctrica\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desdelaterrazadeamador.com\/en\/energia-electrica-por-gravedad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energ\u00eda el\u00e9ctrica por gravedad - Desde la terraza de Amador\" \/>\n<meta property=\"og:description\" content=\"Se sabe que el mayor \u201cproblema\u201d de las energ\u00edas solar y e\u00f3lica es la intermitencia de su suministro, y que cuando no hay sol o viento la energ\u00eda el\u00e9ctrica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desdelaterrazadeamador.com\/en\/energia-electrica-por-gravedad\/\" \/>\n<meta property=\"og:site_name\" content=\"Desde la terraza de Amador\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-25T06:43:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-08T17:23:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Energia-electrica-fusion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Amador Palacios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/edurneamaya\" \/>\n<meta name=\"twitter:site\" content=\"@edurneamaya\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amador Palacios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/energia-electrica-por-gravedad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/energia-electrica-por-gravedad\\\/\"},\"author\":{\"name\":\"Amador Palacios\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"headline\":\"Energ\u00eda el\u00e9ctrica por gravedad\",\"datePublished\":\"2023-05-25T06:43:42+00:00\",\"dateModified\":\"2023-06-08T17:23:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/energia-electrica-por-gravedad\\\/\"},\"wordCount\":490,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"image\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/energia-electrica-por-gravedad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Energia-electrica-fusion.jpg\",\"articleSection\":[\"Sustainable Energy\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/energia-electrica-por-gravedad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/energia-electrica-por-gravedad\\\/\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/energia-electrica-por-gravedad\\\/\",\"name\":\"Energ\u00eda el\u00e9ctrica por gravedad - Desde la terraza de Amador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/energia-electrica-por-gravedad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/energia-electrica-por-gravedad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Energia-electrica-fusion.jpg\",\"datePublished\":\"2023-05-25T06:43:42+00:00\",\"dateModified\":\"2023-06-08T17:23:19+00:00\",\"description\":\"Se sabe que el mayor \u201cproblema\u201d de las energ\u00edas solar y e\u00f3lica es la intermitencia de su suministro, y que cuando no hay sol o viento la energ\u00eda el\u00e9ctrica\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/energia-electrica-por-gravedad\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/energia-electrica-por-gravedad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/energia-electrica-por-gravedad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Energia-electrica-fusion.jpg\",\"contentUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Energia-electrica-fusion.jpg\",\"width\":640,\"height\":427},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/en\\\/energia-electrica-por-gravedad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energ\u00eda el\u00e9ctrica por gravedad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#website\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/\",\"name\":\"Desde la terraza de Amador\",\"description\":\"Reflexiones libres y honestas sobre temas de actualidad social y tecnol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/#\\\/schema\\\/person\\\/0b6966cf66bcc9a2eb35a69e1c074d66\",\"name\":\"Amador Palacios\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"url\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"contentUrl\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\",\"width\":1265,\"height\":899,\"caption\":\"Amador Palacios\"},\"logo\":{\"@id\":\"https:\\\/\\\/desdelaterrazadeamador.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/amador-palacios.jpg\"},\"description\":\"Reflexiones de Amador Palacios sobre temas de Actualidad Social y Tecnol\u00f3gica; otras opiniones diferentes a la m\u00eda son bienvenidas\",\"sameAs\":[\"http:\\\/\\\/desdelaterrazadeamador.com\",\"https:\\\/\\\/es.linkedin.com\\\/in\\\/amador-palacios-499532a\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/edurneamaya\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Energ\u00eda el\u00e9ctrica por gravedad - Desde la terraza de Amador","description":"Se sabe que el mayor \u201cproblema\u201d de las energ\u00edas solar y e\u00f3lica es la intermitencia de su suministro, y que cuando no hay sol o viento la energ\u00eda el\u00e9ctrica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desdelaterrazadeamador.com\/en\/energia-electrica-por-gravedad\/","og_locale":"en_US","og_type":"article","og_title":"Energ\u00eda el\u00e9ctrica por gravedad - Desde la terraza de Amador","og_description":"Se sabe que el mayor \u201cproblema\u201d de las energ\u00edas solar y e\u00f3lica es la intermitencia de su suministro, y que cuando no hay sol o viento la energ\u00eda el\u00e9ctrica","og_url":"https:\/\/desdelaterrazadeamador.com\/en\/energia-electrica-por-gravedad\/","og_site_name":"Desde la terraza de Amador","article_published_time":"2023-05-25T06:43:42+00:00","article_modified_time":"2023-06-08T17:23:19+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Energia-electrica-fusion.jpg","type":"image\/jpeg"}],"author":"Amador Palacios","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/edurneamaya","twitter_site":"@edurneamaya","twitter_misc":{"Written by":"Amador Palacios","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/desdelaterrazadeamador.com\/en\/energia-electrica-por-gravedad\/#article","isPartOf":{"@id":"https:\/\/desdelaterrazadeamador.com\/en\/energia-electrica-por-gravedad\/"},"author":{"name":"Amador Palacios","@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"headline":"Energ\u00eda el\u00e9ctrica por gravedad","datePublished":"2023-05-25T06:43:42+00:00","dateModified":"2023-06-08T17:23:19+00:00","mainEntityOfPage":{"@id":"https:\/\/desdelaterrazadeamador.com\/en\/energia-electrica-por-gravedad\/"},"wordCount":490,"commentCount":0,"publisher":{"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"image":{"@id":"https:\/\/desdelaterrazadeamador.com\/en\/energia-electrica-por-gravedad\/#primaryimage"},"thumbnailUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Energia-electrica-fusion.jpg","articleSection":["Sustainable Energy"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/desdelaterrazadeamador.com\/en\/energia-electrica-por-gravedad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/desdelaterrazadeamador.com\/en\/energia-electrica-por-gravedad\/","url":"https:\/\/desdelaterrazadeamador.com\/en\/energia-electrica-por-gravedad\/","name":"Energ\u00eda el\u00e9ctrica por gravedad - Desde la terraza de Amador","isPartOf":{"@id":"https:\/\/desdelaterrazadeamador.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/desdelaterrazadeamador.com\/en\/energia-electrica-por-gravedad\/#primaryimage"},"image":{"@id":"https:\/\/desdelaterrazadeamador.com\/en\/energia-electrica-por-gravedad\/#primaryimage"},"thumbnailUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Energia-electrica-fusion.jpg","datePublished":"2023-05-25T06:43:42+00:00","dateModified":"2023-06-08T17:23:19+00:00","description":"Se sabe que el mayor \u201cproblema\u201d de las energ\u00edas solar y e\u00f3lica es la intermitencia de su suministro, y que cuando no hay sol o viento la energ\u00eda el\u00e9ctrica","breadcrumb":{"@id":"https:\/\/desdelaterrazadeamador.com\/en\/energia-electrica-por-gravedad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desdelaterrazadeamador.com\/en\/energia-electrica-por-gravedad\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/desdelaterrazadeamador.com\/en\/energia-electrica-por-gravedad\/#primaryimage","url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Energia-electrica-fusion.jpg","contentUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/Energia-electrica-fusion.jpg","width":640,"height":427},{"@type":"BreadcrumbList","@id":"https:\/\/desdelaterrazadeamador.com\/en\/energia-electrica-por-gravedad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/desdelaterrazadeamador.com\/"},{"@type":"ListItem","position":2,"name":"Energ\u00eda el\u00e9ctrica por gravedad"}]},{"@type":"WebSite","@id":"https:\/\/desdelaterrazadeamador.com\/#website","url":"https:\/\/desdelaterrazadeamador.com\/","name":"Desde la terraza de Amador","description":"Free and honest reflections on current social and technological issues","publisher":{"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desdelaterrazadeamador.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/desdelaterrazadeamador.com\/#\/schema\/person\/0b6966cf66bcc9a2eb35a69e1c074d66","name":"Amador Palacios","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","url":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","contentUrl":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg","width":1265,"height":899,"caption":"Amador Palacios"},"logo":{"@id":"https:\/\/desdelaterrazadeamador.com\/wp-content\/uploads\/2022\/01\/amador-palacios.jpg"},"description":"Reflexiones de Amador Palacios sobre temas de Actualidad Social y Tecnol\u00f3gica; otras opiniones diferentes a la m\u00eda son bienvenidas","sameAs":["http:\/\/desdelaterrazadeamador.com","https:\/\/es.linkedin.com\/in\/amador-palacios-499532a","https:\/\/x.com\/https:\/\/twitter.com\/edurneamaya"]}]}},"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/1892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/comments?post=1892"}],"version-history":[{"count":2,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/1892\/revisions"}],"predecessor-version":[{"id":1895,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/posts\/1892\/revisions\/1895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/media\/439"}],"wp:attachment":[{"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/media?parent=1892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/categories?post=1892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desdelaterrazadeamador.com\/en\/wp-json\/wp\/v2\/tags?post=1892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}